{"id":54333,"date":"2016-03-17T08:00:18","date_gmt":"2016-03-17T07:00:18","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/rende-quartieri-al-buio-manomessi-quadri-elettrici-contatori-enel-la-denuncia-del-comune\/"},"modified":"2023-01-17T11:32:58","modified_gmt":"2023-01-17T10:32:58","slug":"81381-rende-quartieri-al-buio-manomessi-quadri-elettrici-contatori-enel-la-denuncia-del-comune","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/81381-rende-quartieri-al-buio-manomessi-quadri-elettrici-contatori-enel-la-denuncia-del-comune\/","title":{"rendered":"Rende quartieri al buio, manomessi quadri elettrici e contatori Enel. La denuncia del Comune (AUDIO)"},"content":{"rendered":"<p><strong>\u201cL\u2019amministrazione comunale annuncia che sono stati afforzati i controlli nei siti presi di mira in questi giorni dagli atti vandalici\u201d.<\/strong><!--more--><br \/>\nRENDE \u2013 \u201cManomessi i quadri elettrici e i contatori dell\u2019Enel in<strong> via Botticelli, via Vanni (di fronte al cimitero), via Ungaretti e via Don Minzoni<\/strong>. Individuato il motivo per cui in questi giorni alcuni quartieri della citt\u00e0 sono rimasti al buio. Si tratta di gesti dietro ai quali si nasconde una matrice di natura dolosa. E\u2019 da escludere, invece, qualsiasi problema di natura tecnica e generale nell\u2019impianto di illuminazione pubblica\u201d. Lo scrive in una nota il <strong>Comune di Rende<\/strong> che annuncia la presentazione di <strong>formale denuncia<\/strong>, rafforzando al tempo stesso gli eventuali controlli sui siti presi di mira e sugli altri potenzialmente sensibili.<br \/>\n\u201cIl problema &#8211; continua la nota &#8211; non sono soltanto le azioni vandaliche, probabilmente dirette contro l\u2019azione politica dell\u2019esecutivo guidato dal sindaco Marcello Manna, ma soprattutto <strong>la sicurezza e l\u2019incolumit\u00e0 degli abitanti di Rende<\/strong>, costretti per lunghe ore a muoversi senza illuminazione nei quartieri in cui vivono o lavorano. Cosa ancora pi\u00f9 grave si \u00e8 verificata al di fuori del Municipio. Anche in questo caso ignoti hanno manomesso e interrotto l\u2019erogazione del gas dell\u2019impianto centralizzato della casa comunale, che per legge si trova fuori dalle mura del palazzo di citt\u00e0. Il mancato funzionamento dell\u2019impianto di riscaldamento del Municipio nei giorni passati \u00e8 da attribuirsi, presumibilmente, ad un&#8217;azione manomissoria. Un fatto grave che desta molta preoccupazione anche fra i dipendenti comunali\u201d.<br \/>\nIl sindaco Manna ha parlato della vicenda ai microfoni di Rlb Radioattiva<\/p>\n<p><span style=\"color: #ff0000;\"><strong>ASCOLTA L&#8217;INTERVISTA<\/strong><\/span><\/p>\n<p>[audio_mp3 url=&#8221;http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2016\/03\/manna-su-danegg-enel.mp3&#8243;]<\/p>\n<h2 style=\"text-align: center;\"><strong>Il sindaco Manna: &#8220;C&#8217;\u00e8 una logica dietro gli atti vandalici&#8221;<\/strong><\/h2>\n<p>\u201cNon sono &#8211; ha sottolineato il sindaco di Rende, Marcello Manna &#8211; episodi isolati. Abbiamo il fondato timore che possa esserci una logica dietro queste azioni vandaliche e non il semplice desiderio di arrecare danno a beni che appartengono alla collettivit\u00e0. <strong>Agiremo con fermezza e intensificheremo i controlli sull\u2019intero territorio<\/strong>. Io stesso presenter\u00f2 formale denuncia, affinch\u00e9 si indaghi subito rispetto a quanto accaduto. Mi auguro che i responsabili vengano individuati nel pi\u00f9 breve tempo possibile\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cL\u2019amministrazione comunale annuncia che sono stati afforzati i controlli nei siti presi di mira in questi giorni dagli atti vandalici\u201d.<\/p>\n","protected":false},"author":22,"featured_media":54334,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,571,44],"tags":[],"class_list":["post-54333","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-in-evidenza","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/54333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=54333"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/54333\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/54334"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=54333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=54333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=54333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}