{"id":54379,"date":"2016-03-17T17:06:17","date_gmt":"2016-03-17T16:06:17","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/incendiata-lauto-dellassessore-alla-cultura-rende-vado-avanti\/"},"modified":"2023-01-17T11:33:03","modified_gmt":"2023-01-17T10:33:03","slug":"81585-incendiata-lauto-dellassessore-alla-cultura-rende-vado-avanti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/81585-incendiata-lauto-dellassessore-alla-cultura-rende-vado-avanti\/","title":{"rendered":"Incendiata l&#8217;auto dell&#8217;assessore alla Cultura di Rende: &#8220;Vado avanti&#8221; (AUDIO)"},"content":{"rendered":"<p><strong>La Volkswagen Touareg di Vittorio Toscano \u00e8 stata data alle fiamme nella notte.<\/strong><!--more--><\/p>\n<p style=\"text-align: left;\">RENDE (CS) &#8211; Episodio di verosimile natura intimidatoria a Rende. Ignoti nella notte hanno cosparso di liquido infiammabile e dato alle fiamme l&#8217;auto dell&#8217;assessore alla Cultura del Comune di Rende Vittorio Toscano. La vettura si trovava parcheggiata in via Don Minzoni sotto l&#8217;abitazione che l&#8217;assessore condivide con la propria compagna. Ad allertarlo sono stati i vicini di casa mentre i Vigili del Fuoco erano gi\u00e0 al lavoro per domare il rogo. L&#8217;automobile dopo l&#8217;incendio \u00e8 andata completamente distrutta. Sul caso indagano i carabinieri di Rende che hanno gi\u00e0 provveduto ad acquisire le immagini del sistema di videosorveglianza presente nei pressi del condiminio. L&#8217;assessore a cui il sindaco Marcello Manna ha affidato le deleghe al Commercio, Turismo, Politiche Agricole, Spettacoli ed Eventi afferma di non aver alcuna intenzione di lasciare il proprio in carico nonostante la vicenda rappresenti una chiara minaccia. &#8220;Ci hanno fatto questa sorpresa stanotte, &#8211; ha affermato l&#8217;assessore &#8211; personalmente non avevo mai avuto problemi del genere. Non sono stato mai esposto ad alcun tipo di pressione. <strong>Non mi voglio sbilanciare, ma credo che il fatto che stiamo lavorando bene non piaccia a qualcuno.<\/strong> Lavoro nella massima trasparenza, per il bene comune, non ho mai pensato a me stesso, ma ai giovani e a chi vuole fare crescere questo territorio. Non possiedo nessuna attivit\u00e0 commerciale di rilievo. Anzi. Sono un consulente specializzato in rapporti con l&#8217;estero lavoro ora per il Comune di Rende e fino a poco tempo fa prestavo servizio in Regione. Finch\u00e9 il sindaco mi dar\u00e0 fiducia andr\u00f2 avanti&#8221;.<\/p>\n<p style=\"text-align: justify;\">In merito l&#8217;assessore <strong>Toscano<\/strong> \u00e8 intervenuto ai microfoni di <strong>Rlb Radioattiva<\/strong> per commentare la spiacevole e grave vicenda che lo ha interessato<\/p>\n<p style=\"text-align: left;\"><span style=\"color: #ff0000;\"><strong>ASCOLTA L&#8217;INTERVISTA<\/strong><\/span><br \/>\n[audio_mp3 url=&#8221;http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2016\/03\/Vittorio-toscano.mp3&#8243;]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Volkswagen Touareg di Vittorio Toscano \u00e8 stata data alle fiamme nella notte.<\/p>\n","protected":false},"author":18,"featured_media":54380,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,571,44],"tags":[],"class_list":["post-54379","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-in-evidenza","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/54379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=54379"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/54379\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/54380"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=54379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=54379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=54379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}