{"id":54546,"date":"2016-03-21T14:03:02","date_gmt":"2016-03-21T13:03:02","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/console-generale-degli-stati-uniti-damerica-arriva-cosenza\/"},"modified":"2023-01-17T11:59:48","modified_gmt":"2023-01-17T10:59:48","slug":"82150-console-generale-degli-stati-uniti-damerica-arriva-cosenza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/82150-console-generale-degli-stati-uniti-damerica-arriva-cosenza\/","title":{"rendered":"Il Console Generale degli Stati Uniti d&#8217;America arriva a Cosenza"},"content":{"rendered":"<p><strong>Colombia A. Barrosse sar\u00e0 accolta domani a Palazzo dei Bruzi dal Commissario Angelo Carbone.<\/strong><br \/>\n&nbsp;<br \/>\n<!--more--><\/p>\n<p>COSENZA \u2013 Sar\u00e0 ricevuto dal Commissario straordinario <strong>Angelo Carbone<\/strong> a<strong> Palazzo dei Bruzi<\/strong> il <strong>Console Generale degli Stati Uniti d&#8217;America nel Sud Italia, Colombia A. Barrosse<\/strong>. L\u2019incontro, in programma domani, \u00e8 fissato per le <strong>15.30<\/strong>.<br \/>\n&nbsp;<\/p>\n<p><strong>Ha lavorato al Dipartimento di Stato a Washington<\/strong><!--more--><\/p>\n<p>Nata a <strong>New Orleans<\/strong>, in Louisiana, e cresciuta tra <strong>Colombia, Uruguay e Panama<\/strong>, dove suo padre lavorava per l\u2019<strong>United States Agency for International Development<\/strong>, Colombia A. Barrosse ha iniziato la sua carriera diplomatica nel 1989 e attualmente ha il grado di Consigliere. Ha lavorato nelle ambasciate di <strong>Santo Domingo<\/strong> (1989-91), <strong>Madrid<\/strong> (1991-94), <strong>Buenos Aires<\/strong> (1994-96), <strong>Lima<\/strong> (1998-2001) e <strong>Parigi<\/strong> (2003-07), spaziando dal settore consolare a quello degli affari pubblici a quello politico.<br \/>\n<strong>In tre occasioni ha lavorato al Dipartimento di Stato a Washington<\/strong>, tra l\u2019altro come Assistente Speciale del Segretario di Stato <strong>Madeleine Albright<\/strong>. Il suo ultimo incarico, prima di assumere quello di Console Generale nel Sud Italia, \u00e8 stato quello di Console Generale a Port-au-Prince ad Haiti. Ha una laurea in biologia ed una in giurisprudenza, conseguita presso il College of William &amp; Mary. Il suo insediamento al Consolato Generale degli Stati Uniti d&#8217;America, a Napoli, risale all&#8217;agosto del 2013.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Colombia A. Barrosse sar\u00e0 accolta domani a Palazzo dei Bruzi dal Commissario Angelo Carbone. &nbsp;<\/p>\n","protected":false},"author":22,"featured_media":54547,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42,571],"tags":[],"class_list":["post-54546","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/54546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=54546"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/54546\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/54547"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=54546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=54546"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=54546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}