{"id":54712,"date":"2016-03-28T06:55:29","date_gmt":"2016-03-28T04:55:29","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/sergio-cammariere-inaugurera-progetto-eccellenze-locresi\/"},"modified":"2023-01-17T12:00:08","modified_gmt":"2023-01-17T11:00:08","slug":"82818-sergio-cammariere-inaugurera-progetto-eccellenze-locresi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/82818-sergio-cammariere-inaugurera-progetto-eccellenze-locresi\/","title":{"rendered":"Sergio Cammariere inaugurer\u00e0 progetto su eccellenze locresi"},"content":{"rendered":"<p><strong>Cammariere sar\u00e0 il protagonista della prima edizione dell&#8217;evento &#8220;Dalla Pace del mare lontano &#8211; Magna Grecia terra di Pace e Cultura&#8221;.<\/strong><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>LOCRI (RC) &#8211; Il prossimo 24 aprile alle 21,00, nella Corte del Palazzo di Citt\u00e0, il concerto del cantautore crotonese con la sua band inaugurer\u00e0 un progetto che intende, attraverso la grande musica d&#8217;autore, sottolineare le molteplici eccellenze di Locri e del suo vasto comprensorio, dalla storia alla cultura, alle straordinarie bellezze paesaggistiche di uno dei luoghi pi\u00f9 incantevoli e incontaminati del Paese. Sul palcoscenico, Cammariere sar\u00e0 accompagnato dai suoi affiatatissimi musicisti: Amedeo Ariano, batteria, Luca Bulgarelli, contrabasso, Bruno Marcozzi, percussioni. Lo scopo \u00e8 quello di portare un messaggio che arriva direttamente dall&#8217;arte, dalla grande musica di <strong>Sergio Cammariere<\/strong>, un calabrese che ha dato lustro alla sua terra, conquistando sempre pi\u00f9 spazi e trovando costantemente riscontro positivo nel giudizio del pubblico e della critica. &#8220;Dalla Pace del Mare Lontano&#8221; \u00e8 anche\u00a0il titolo di un brano scritto da Cammariere.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;Sergio Cammariere &#8211; afferma l&#8217;assessore Sofia &#8211; \u00e8 un vero chansonnier; un talento straordinario che alla Calabria dedica tempo ed amore. Anche quando non \u00e8\u00a0in giro per il mondo e pur non vivendo pi\u00f9 a Crotone, non dimentica la sua radice ed il suo territorio. <strong>Magna Grecia terra di Pace e Cultura<\/strong> &#8211; aggiunge Anna Rosa Sofia &#8211; \u00e8\u00a0la sintesi perfettamente descrittiva di un percorso culturale e storico che, nella musica di Cammariere, trova massima esaltazione e cancella i molti luoghi comuni che accompagnano giornalmente la Calabria, terra prevalentemente di saggezza e solarit\u00e0 che la mafia ed il malcostume possono solo temporaneamente offuscare&#8221;. Il concerto di Cammariere rientra nell&#8217;ambito di un programma avviato dall&#8217;Amministrazione Comunale con il fine di segnare Locri con eventi culturali di assoluto richiamo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cammariere sar\u00e0 il protagonista della prima edizione dell&#8217;evento &#8220;Dalla Pace del mare lontano &#8211; Magna Grecia terra di Pace e Cultura&#8221;.<\/p>\n","protected":false},"author":22,"featured_media":54713,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[40,34],"tags":[],"class_list":["post-54712","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-spettacolo","category-magazine"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/54712","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=54712"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/54712\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/54713"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=54712"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=54712"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=54712"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}