{"id":5486,"date":"2012-10-11T11:23:14","date_gmt":"2012-10-11T09:23:14","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=5486"},"modified":"2023-01-17T13:38:46","modified_gmt":"2023-01-17T12:38:46","slug":"2037-calabria-appello-di-un-gruppo-di-sindaci-per-mobilitazione","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/2037-calabria-appello-di-un-gruppo-di-sindaci-per-mobilitazione\/","title":{"rendered":"Calabria: appello di un gruppo di sindaci per mobilitazione"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-size: 12px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\">La Calabria sta vivendo uno dei suoi momenti pi\u00f9 difficili. La situazione sociale ed economica \u00e8 tra le pi\u00f9 gravi che la regione abbia vissuto.<\/span><\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\"> L&#8217;occupazione \u00e8 ai minimi storici e il tessuto industriale ridotto ai minimi termini. La disoccupazione \u00e8 una piaga sempre pi\u00f9 grande&nbsp; e che riguarda in misura enorme i nostri giovani e le nostre donne.&nbsp; A questa realt\u00e0 drammatica non d\u00e0 risposte il Governo nazionale alle cui politiche di rigore non hanno ancora corrisposto significative e credibili misure per lo sviluppo, n\u00e9 tanto meno il governo regionale che \u00e8 corresponsabile non solo della crisi sociale e culturale ma anche istituzionale e morale che sta vivendo la Calabria.<\/span><br style=\"margin: 0px; padding: 0px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\" \/><span style=\"font-size: 12px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\">E&#8217; questa grande preoccupazione per la nostra terra e per i nostri concittadini che ci spinge a raccogliere la sfida positiva lanciata in questi giorni da Cgil, Cisl e Uil in occasione della mobilitazione per il prossimo sabato 13 ottobre a Catanzaro alla presenza dei segretari generali Susanna Camusso, Raffaele Bonanni e Luigi Angeletti.&nbsp;<\/span><br style=\"margin: 0px; padding: 0px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\" \/><span style=\"font-size: 12px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\">L&#8217;iniziativa che \u00e8 stata promossa dai sindacati per difendere l&#8217;occupazione, per la crescita e il rilancio della Calabria e del Sud, \u00e8 sacrosanta e lancia al tempo stesso un allarme ed una proposta. L&#8217;allarme per la condizione difficilissima che vive il mezzogiorno ed in modo particolare la Calabria, come testimoniano anche i dati della Svimez resi noti nei giorni scorsi, e la proposta di una fuoriuscita dalla crisi impossibile senza il Sud. Nei giorni scorsi, a Lamezia i sindaci italiani riuniti nel loro Consiglio nazionale, al quale hanno partecipato molti sindaci calabresi, hanno lanciato idee e proposte significative su questo tema. Ed ecco perch\u00e9 ci sembra giusto oggi rilanciare quelle proposte discusse a Lamezia mettendole in campo in occasione della grande mobilitazione sindacale di sabato prossimo. Ci rivolgiamo per questo ai nostri colleghi sindaci di tutta la Calabria e alle nostre concitttadine e ai nostri concittadini affinch\u00e9 insieme si faccia sentire forte e chiara la voce della Calabria che vuole lavoro, sviluppo, legalit\u00e0 e ci auguriamo che il Governo e la Regione ascoltino con attenzione e seriet\u00e0 queste voci e adottino i provvedimenti urgenti che la crisi e la condizione della nostra terra sollecitano.&nbsp;<\/span><br style=\"margin: 0px; padding: 0px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\" \/><span style=\"font-size: 12px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\">Sindaco Pizzo, Gianluca Callipo<\/span><br style=\"margin: 0px; padding: 0px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\" \/><span style=\"font-size: 12px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\">Sindaco Decollatura, Anna Maria Cardamone<\/span><br style=\"margin: 0px; padding: 0px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\" \/><span style=\"font-size: 12px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\">Sindaco Isola Capo Rizzuto, Carolina Girasole<\/span><br style=\"margin: 0px; padding: 0px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\" \/><span style=\"font-size: 12px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\">Sindaco Monasterace, Maria Carmela Lanzetta<\/span><br style=\"margin: 0px; padding: 0px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\" \/><span style=\"font-size: 12px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\">Sindaco Riace, Mimmo Lucano<\/span><br style=\"margin: 0px; padding: 0px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\" \/><span style=\"font-size: 12px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\">Sindaco Acquaformosa, Giovanni Manoccio<\/span><br style=\"margin: 0px; padding: 0px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\" \/><span style=\"font-size: 12px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\">Sindaco Lamezia Terme, Gianni Speranza<\/span><br style=\"margin: 0px; padding: 0px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\" \/><span style=\"font-size: 12px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\">sindaco Rosarno, Elisabetta Tripodi<\/span><br style=\"margin: 0px; padding: 0px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\" \/><span style=\"font-size: 12px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\">Sindaco Crotone, Peppino Vallone<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\">&nbsp;<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\">Strill.it<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Calabria sta vivendo uno dei suoi momenti pi\u00f9 difficili. La situazione sociale ed economica \u00e8 tra le pi\u00f9 gravi che la regione abbia vissuto.<\/p>\n","protected":false},"author":22,"featured_media":5487,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17,5],"tags":[],"class_list":["post-5486","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria","category-old"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/5486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=5486"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/5486\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/5487"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=5486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=5486"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=5486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}