{"id":55074,"date":"2016-04-05T05:00:05","date_gmt":"2016-04-05T03:00:05","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/m5s-mentre-paolini-e-magorno-fanno-la-corte-ai-gentile-noi-pensiamo-al-programma\/"},"modified":"2023-01-17T12:00:54","modified_gmt":"2023-01-17T11:00:54","slug":"84374-m5s-mentre-paolini-e-magorno-fanno-la-corte-ai-gentile-noi-pensiamo-al-programma","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/84374-m5s-mentre-paolini-e-magorno-fanno-la-corte-ai-gentile-noi-pensiamo-al-programma\/","title":{"rendered":"M5S: &#8220;Mentre Paolini e Magorno fanno la corte ai Gentile, noi pensiamo al programma&#8221;"},"content":{"rendered":"<p><strong>Il candidato sindaco di Cosenza del Movimento 5 Stelle, Gustavo Coscarelli all&#8217;attacco di Pd e Pse: &#8220;Loro pensano a spartirsi le poltrone, noi proponiamo aria di cambiamento&#8221;.<\/strong><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Il segretario regionale del <strong>Pd Ernesto Magorno<\/strong> le sta provando tutte. Vuole fare entrare ad ogni costo i fratelli <strong>Pino e Antonio Gentile<\/strong>\u00a0nell&#8217;Alleanza Civica messa in piedi per sostenere il candidato sindaco di <strong>Cosenza<\/strong> <strong>Lucio Presta<\/strong> in vista delle amministrative di giugno. La corte di Magorno ai rappresentanti calabresi del <strong>Nuovo centrodestra<\/strong>\u00a0\u00e8 spietata e punta a bruciare sul tempo l&#8217;altro candidato sindaco <strong>Enzo Paolini<\/strong>, che da tempo ha allacciato un rapporto molto stretto con il vicepresidente del Consiglio regionale e con il sottosegretario allo Sviluppo economico. Nell&#8217;attesa di capire chi la spunter\u00e0 tra i due contendenti, c&#8217;\u00e8 da registrare, sulla vicenda, il duro intervento del <strong>Movimento 5 Stelle<\/strong> con <strong>Gustavo Coscarelli<\/strong>. &#8220;Alleanze, trattative, poltrone &#8211; dichiara il candidato sindaco pentastellato -. Non si fa altro che parlare di questo. Il segretario regionale del Pd Ernesto Magorno chiede ai fratelli Gentile di sostenere il candidato a sindaco Presta in una sorta di ultima chiamata. I fratelli Gentile contesi dunque da una parte da Magorno e dall\u2019altra da Paolini. Il nostro programma \u00e8 pronto stiamo considerando gli ultimi dettagli, l\u2019abbiamo scritto con i cittadini e a breve verr\u00e0 reso noto a tutti. L\u2019auspicio dei 5 Stelle \u00e8 che il dibattito tra i vari candidati avversari si sposti sui programmi, sui temi per migliorare Cosenza e non sulle (solite) politiche di palazzo&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il candidato sindaco di Cosenza del Movimento 5 Stelle, Gustavo Coscarelli all&#8217;attacco di Pd e Pse: &#8220;Loro pensano a spartirsi le poltrone, noi proponiamo aria di cambiamento&#8221;.<\/p>\n","protected":false},"author":22,"featured_media":55075,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42,571],"tags":[],"class_list":["post-55074","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/55074","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=55074"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/55074\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/55075"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=55074"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=55074"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=55074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}