{"id":55076,"date":"2016-04-04T13:19:43","date_gmt":"2016-04-04T11:19:43","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/migranti-a-cosenza-il-progetto-radici-a-scuola\/"},"modified":"2023-01-17T12:00:54","modified_gmt":"2023-01-17T11:00:54","slug":"84377-migranti-a-cosenza-il-progetto-radici-a-scuola","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/84377-migranti-a-cosenza-il-progetto-radici-a-scuola\/","title":{"rendered":"Migranti, a Cosenza il progetto &#8216;Radici a Scuola&#8217;"},"content":{"rendered":"<p><strong>Si tratta di un&#8217;iniziativa promossa dal Dipartimento per le libert\u00e0 civili e l&#8217;immigrazione del Ministero dell&#8217;Interno e dalla trasmissione televisiva di Rai Tre &#8216;Radici&#8217;, curata da Davide Demichelis, che ne \u00e8 anche autore e conduttore.<\/strong><br \/>\n&nbsp;<br \/>\n<!--more--><\/p>\n<p>COSENZA &#8211; Il progetto &#8216;<strong>Radici a scuola<\/strong>&#8216; arriva a Cosenza. L&#8217;amministrazione comunale, insieme al <strong>Liceo Statale &#8216;Lucrezia Della Valle&#8217;<\/strong>, ha infatti organizzato per\u00a0 per <strong>domani, marted\u00ec 5 aprile<\/strong>, un incontro di sensibilizzazione sul tema dell&#8217;integrazione dei migranti. L&#8217;appuntamento \u00e8 fissato per le ore 10,15 nella sede dello stesso Liceo. A portare il saluto istituzionale del Comune di Cosenza sar\u00e0 la dottoressa <strong>Emanuela Greco<\/strong>, subcommissaria di <strong>Palazzo dei Bruzi<\/strong>, in rappresentanza del <strong>Commissario straordinario Angelo Carbone<\/strong>. Il Comune di Cosenza si era gi\u00e0 occupato, qualche anno fa, attraverso il Settore Fondi Comunitari, di questa specifica tematica con il progetto &#8216;A scuola di integrazione e convivenza: nessuno escluso&#8217;, finalizzato proprio a favorire l&#8217;integrazione dei cittadini stranieri, l&#8217;integrazione scolastica e l&#8217;inclusione sociale dei pi\u00f9 giovani. Nel corso dell&#8217;incontro sar\u00e0 proiettato un reportage della serie televisiva &#8216;Radici&#8217;, in onda da quattro stagioni su <strong>Rai Tre<\/strong>, mentre \u00e8 ai nastri di partenza la produzione della sua quinta stagione. L&#8217;esperienza di &#8216;Radici&#8217; entra nelle scuole superiori italiane come occasione di conoscenza e testimonianza per far incontrare gli studenti con le storie di immigrati regolari, che costituiscono circa il 7% della popolazione italiana. Alla giornata cosentina prenderanno parte, per un confronto diretto con gli studenti, sia <strong>Davide Demichelis<\/strong> che <strong>Nela Lucic<\/strong>, che \u00e8\u00a0stata ospite di una puntata di &#8216;Radici&#8217;.<br \/>\n&nbsp;<\/p>\n<p>Nei reportage realizzati per &#8216;Radici&#8217; gli immigrati che vivono in Italia fanno ritorno nei loro Paesi di origine in un continuo oscillare tra memoria e presente, tra la cultura, la politica e la situazione sociale del loro Paese. Ogni protagonista diventa una guida d&#8217;eccezione: parla italiano e comunica direttamente le sensazioni nel ritrovare i luoghi natali e la sua gente, spiegando le ragioni che lo hanno spinto a lasciare la propria terra per trasferirsi in Italia. Protagonista della giornata di Cosenza sar\u00e0 Nela Lucic, che oggi fa l&#8217;attrice con piccole parti in film per la televisione ed il cinema. Nata nel 1976 a <strong>Bugojno<\/strong>, un paese nel cuore della <strong>Bosnia-Erzegovina<\/strong> dove ha vissuto fino all&#8217;adolescenza, Nela \u00e8 arrivata in Italia, a Gorizia, nel 1991, poco prima che scoppiassero i combattimenti di cui i suoi parenti e i suoi amici sono stati testimoni. Terminati gli studi superiori, Nela Lucic lascia Gorizia per Gaeta, dove vivono alcune cugine e sceglie infine di vivere a <strong>Roma<\/strong> dove si laurea in lingue e letteratura straniera all&#8217;<strong>Universit\u00e0 &#8216;La Sapienza&#8217;<\/strong>. Grazie a &#8216;Radici&#8217; Nela, ancora molto legata alla sua cultura e alle sue tradizioni, fa ritorno in <strong>Bosnia<\/strong> dopo vent&#8217;anni. Con Nela Lucic i ragazzi del Liceo Della Valle di Cosenza potranno approfondire i temi legati alle persecuzioni, alla guerra in Bosnia e alle tradizioni e cultura del suo Paese. I ragazzi, al termine dell&#8217;esperienza, ai fini della prosecuzione del dibattito anche sul web, saranno invitati ad intervenire sulla pagina Facebook di &#8216;Radici&#8217; e sul sito www.radiciascuola.it pubblicando le fotografie della giornata cosentina, le video interviste realizzate all&#8217;autore del programma e alla protagonista e altro materiale proposto dagli stessi studenti, come racconti di viaggi o di storie di immigrazione della citt\u00e0. Oltre alla proiezione del documentario la giornata cosentina del progetto &#8216;Radici a scuola&#8217; prevede anche l&#8217;allestimento di una piccola mostra con pannelli che raccontano di alcuni Paesi protagonisti della serie tv di Rai Tre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si tratta di un&#8217;iniziativa promossa dal Dipartimento per le libert\u00e0 civili e l&#8217;immigrazione del Ministero dell&#8217;Interno e dalla trasmissione televisiva di Rai Tre &#8216;Radici&#8217;, curata da Davide Demichelis, che ne \u00e8 anche autore e conduttore. &nbsp;<\/p>\n","protected":false},"author":22,"featured_media":55077,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42,571],"tags":[],"class_list":["post-55076","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/55076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=55076"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/55076\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/55077"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=55076"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=55076"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=55076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}