{"id":55084,"date":"2016-04-04T15:20:36","date_gmt":"2016-04-04T13:20:36","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/calabria-sciopero-generale-dei-lavoratori-della-pubblica-amministrazione\/"},"modified":"2023-01-17T12:00:55","modified_gmt":"2023-01-17T11:00:55","slug":"84393-calabria-sciopero-generale-dei-lavoratori-della-pubblica-amministrazione","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/84393-calabria-sciopero-generale-dei-lavoratori-della-pubblica-amministrazione\/","title":{"rendered":"In Calabria sciopero generale dei lavoratori della pubblica amministrazione"},"content":{"rendered":"<p><strong>I sindacati annunciano una grande mobilitazione per i primi di maggio: \u201cSituazione ormai ingestibile\u201d.<\/strong><!--more--><br \/>\n&nbsp;<\/p>\n<p>CATANZARO \u2013 Funzione pubblica\u00a0<strong>Cgil, Cisl e Uil<\/strong> annunciato per i primi di maggio uno sciopero generale di tutti i dipendenti del pubblico impiego calabrese. La decisione, sostengono i sindacati, \u00e8 stata presa alla luce una situazione, per i dipendenti pubblici di ogni settore, ormai ingestibile. \u201c<strong>Troppe vertenze &#8211; evidenziano &#8211; come tante ferite aperte nel pubblico, a pagarne le spese i lavoratori ma anche la qualit\u00e0 dei servizi<\/strong> e quindi gli utenti stessi, ovvero tutti i cittadini calabresi&#8221;.<br \/>\n&nbsp;<\/p>\n<p>I numeri, intanto, che parlano da soli, con, negli ultimi anni, in Italia, almeno duecentomila lavoratori in meno nel settore pubblico, e in Calabria una cifra che si attesta intorno ai quindici mila, seppure un dato non certificato perch\u00e9 le stesse amministrazioni pubbliche non lo rendono preciso in un deficit di programmazione e quindi, anche, di trasparenza. Tanti, troppi i settori piegati, a partire dalla sanit\u00e0, principale vulnus calabrese, &#8220;con lavoratori &#8211; ha sottolineato il<strong> segretario Funzione pubblica Cgil Calabria Alfredo Iorn<\/strong>o &#8211; non pagati da troppi mesi, nel pubblico cos\u00ec, come nel privato, con i dipendenti delle Province in mobilit\u00e0, anch&#8217;essi non ricevono lo stipendio da diversi mesi, e con un futuro incerto, sempre pi\u00f9 numerose le vertenze in corso, con una precarizzazione e una esternalizzazione del pubblico di anno in anno pi\u00f9 massiccia, \u00e8 per questo che, unitariamente, insieme a Funzione pubblica Cisl e Uil, gridiamo &#8220;ora basta&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I sindacati annunciano una grande mobilitazione per i primi di maggio: \u201cSituazione ormai ingestibile\u201d.<\/p>\n","protected":false},"author":22,"featured_media":55085,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,571],"tags":[],"class_list":["post-55084","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/55084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=55084"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/55084\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/55085"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=55084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=55084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=55084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}