{"id":55164,"date":"2016-04-06T09:43:08","date_gmt":"2016-04-06T07:43:08","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/a-rende-cattivo-odore-e-aria-irrespirabile-e-il-tar-da-ragione-a-legnochimica\/"},"modified":"2023-01-17T12:01:03","modified_gmt":"2023-01-17T11:01:03","slug":"84629-a-rende-cattivo-odore-e-aria-irrespirabile-e-il-tar-da-ragione-a-legnochimica","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/84629-a-rende-cattivo-odore-e-aria-irrespirabile-e-il-tar-da-ragione-a-legnochimica\/","title":{"rendered":"A Rende cattivo odore e aria irrespirabile&#8230; e il Tar d\u00e0 ragione a Legnochimica"},"content":{"rendered":"<p><strong>Sono giorni che Rende&#8230; puzza! E ancora non si \u00e8 capito, anche se il sospetto ricade ancora sui laghi dell&#8217;ex Legnochimica,\u00a0da dove arriva quell&#8217;odore nauseabondo.<\/strong><\/p>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>RENDE (CS) &#8211; Quelle che arrivano chiare e determinate sono\u00a0le segnalazioni degli <strong>utenti<\/strong>, di <strong>cittadini<\/strong> e <strong>lavoratori<\/strong>\u00a0della zona industriale che parlano di<strong> aria irrespirabile<\/strong>, di un forte cattivo odore che pervade la <strong>&#8216;Citt\u00e0 di Rende&#8217;<\/strong> da giorni. Un odore nauseabondo, forte, \u00a0che arriva dalla zona industriale di contrada Lecco. Alcuni rendesi che abitano in quella zona, parlano anche di una sorta di colonna di fumo, avvistata nei pressi dell<strong>&#8216;ex stabilimento di Legnochimic<\/strong>a. Secondo quanto si \u00e8 appreso in molti hanno contattato <strong>vigili urbani, vigili del fuoco e forze dell&#8217;ordine.<\/strong><br \/>\nAnche <strong>l&#8217;Associazione Crocevia,<\/strong> \u00e8 intervenuta attraverso un post sulla propria pagina Facebook per esprimere la disillusione di una zona che sembrava non dare problemi, ma ecco come invece, da qualche giorno, quella &#8216;puzza&#8217; sia tornata al naso dei cittadini. Da sottolineare inoltre che nella zona industriale non c&#8217;\u00e8 solo il &#8216;problema&#8217; Legnochimica, ma esistono e lavorano diverse attivit\u00e0 industriali la cui attivit\u00e0 evidentemente non viene monitorata e controllata. E sulla pagina si sottolinea come <em>&#8220;solo con forme di protesta estrema si riesce a far rispettare le regole.\u00a0Attenti per\u00f2, la gente st\u00e0 perdendo la pazienza. Un&#8217;amara considerazione, cambiamo gli attori ma il film \u00e8 sempre lo stesso&#8221;<\/em>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-84642 aligncenter\" src=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2016\/04\/crocevia-legnochimica.jpg\" alt=\"crocevia legnochimica\" width=\"418\" height=\"439\" title=\"\"><\/p>\n<p>Intanto <strong>Domenico Miceli<\/strong>, consigliere comunale del <strong>Movimento 5 Stelle<\/strong>, ai microfoni di <strong>Rlb Radioattiva sottolinea due aspetti<\/strong>. Il primo \u00e8 di aver intenzione, ancora una volta, di far intervenire l&#8217;Arpacal, che per\u00f2 ad agosto, interpellata, nella relazione indicava l&#8217;assenza di cattivo odore nella zona industriale di Rende. Altro aspetto che complica la questione Legnochimica \u00e8 anche, ha spiegato Miceli, la <strong>bocciatura dell&#8217;ordinanza da parte del Tar<\/strong> che ha dato ragione all&#8217;ex azienda <strong>Legnochimica<\/strong>. Pertanto di bonifica del sito non se ne parla ed inoltre, gli altri stabilimenti industriali che trasformano determinati prodotti e continuano ad operare senza controllo.<\/p>\n<p><span style=\"color: #ff0000;\"><strong>ASCOLTA L&#8217;INTERVISTA<\/strong><\/span><br \/>\n[audio_mp3 url=&#8221;http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2016\/04\/Domenico-Miceli-puzza-area-industriale.mp3&#8243;]<\/p>\n<p><strong>Per ora la puzza non si sa bene da dove arrivi,<\/strong> potrebbe essere legata ai laghi di Legnochimica o ad ad altri impianti che sono invece attivi e il Comune deve richiedere il rispetto di tutte le regole. Il problema c&#8217;\u00e8, <strong>l&#8217;odore si sente<\/strong> e <strong>supera i confini rendesi arrivando anche a Montalt<\/strong>o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sono giorni che Rende&#8230; puzza! E ancora non si \u00e8 capito, anche se il sospetto ricade ancora sui laghi dell&#8217;ex Legnochimica,\u00a0da dove arriva quell&#8217;odore nauseabondo.<\/p>\n","protected":false},"author":19,"featured_media":55165,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,571,44],"tags":[],"class_list":["post-55164","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-in-evidenza","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/55164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=55164"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/55164\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/55165"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=55164"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=55164"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=55164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}