{"id":55291,"date":"2016-04-08T11:31:29","date_gmt":"2016-04-08T09:31:29","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/aids-ricercatori-delluniversita-della-calabria-scoprono-molecole-anti-hiv\/"},"modified":"2023-01-17T12:01:16","modified_gmt":"2023-01-17T11:01:16","slug":"85156-aids-ricercatori-delluniversita-della-calabria-scoprono-molecole-anti-hiv","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/85156-aids-ricercatori-delluniversita-della-calabria-scoprono-molecole-anti-hiv\/","title":{"rendered":"AIDS: ricercatori dell&#8217;Universit\u00e0 della Calabria, scoprono molecole anti-HIV"},"content":{"rendered":"<p><strong>Un nuovo farmaco contro l&#8217;AIDS potr\u00e0 essere creato grazie allo studio dei ricercatori dell&#8217;Unical.<\/strong><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">RENDE &#8211; Nuova scoperta dai laboratori dell&#8217;Universit\u00e0 della Calabria. Un eccellente studio dei ricercatori in forze all&#8217;Unical ha portato ad individuare una strategia di sintesi di nuove molecole che presentano una significativa attivit\u00e0 antagonista nei confronti del virus HIV, responsabile dell&#8217;AIDS. L&#8217;importantissima ricerca che potrebbe avere notevoli risvolti in ambito sanitario \u00e8 stata messa a punto dal gruppo di ricerca dell&#8217;Universit\u00e0 della Calabria coordinato dal professore Bartolo Gabriele in forze presso il Laboratorio di Chimica Organica Sintetica e Industriale del Dipartimento di Chimica e Tecnologie Chimiche. Le ricerche sono state condotte in collaborazione con altri istituti di ricerca italiani, in particolare con i gruppi di ricerca dell&#8217;Universita&#8217; di Parma, dell&#8217;Universita&#8217; di Roma &#8211; Tor Vergata, dell&#8217;Istituto di Farmacologia Traslazionale del CNR di Roma e dell&#8217;Universita&#8217; di Messina. &#8220;Le ricerche &#8211; spiega una nota dell&#8217;ateneo calabrese &#8211; hanno permesso di individuare una nuova classe di principi attivi caratterizzati da una specifica attivita&#8217; anti-HIV e da un grado di tossicita&#8217; particolarmente basso, che <strong>potra&#8217; pertanto consentire di effettuare trattamenti cronici prolungati dei soggetti che hanno contratto l&#8217;infezione, minimizzando gli effetti collaterali del nuovo farmaco.<\/strong> I risultati delle ricerche sono stati oggetto di deposito di un brevetto congiunto dell&#8217;Universita&#8217; della Calabria e degli altri istituti che hanno partecipato allo studio. Gli ulteriori sviluppi delle ricerche attualmente in corso &#8211; si legge &#8211; potranno permettere di individuare molecole ancora piu&#8217; attive, per le quali sono previste delle sperimentazioni in vivo che potranno portare alla formulazione di un nuovo efficiente farmaco per il trattamento dell&#8217;AIDS&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un nuovo farmaco contro l&#8217;AIDS potr\u00e0 essere creato grazie allo studio dei ricercatori dell&#8217;Unical.<\/p>\n","protected":false},"author":22,"featured_media":55292,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[571,7],"tags":[],"class_list":["post-55291","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-universita"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/55291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=55291"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/55291\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/55292"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=55291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=55291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=55291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}