{"id":55527,"date":"2016-04-14T09:57:18","date_gmt":"2016-04-14T07:57:18","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cosciotto-di-agnello-allarancia-preparato-con-il-metodo-slow-cooking\/"},"modified":"2023-01-17T12:01:42","modified_gmt":"2023-01-17T11:01:42","slug":"86198-cosciotto-di-agnello-allarancia-preparato-con-il-metodo-slow-cooking","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/86198-cosciotto-di-agnello-allarancia-preparato-con-il-metodo-slow-cooking\/","title":{"rendered":"Cosciotto di agnello all&#8217;arancia preparato con il metodo Slow Cooking"},"content":{"rendered":"<p><strong>Dedicheremo qualche settimana al metodo della cottura a bassa temperatura\u00a0utilizzata\u00a0in tempi antichissimi\u00a0per mezzo di\u00a0una fonte di calore naturale e materiali\u00a0come la terracotta.<\/strong><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>Oggi \u00e8 disponibile la pentola slow cooking che simula questa tecnica di cottura e sta tornando in voga da un p\u00f2 di tempo a questa parte. Le Slow Cooking di solito sono pentole in ceramica alimentate a energia elettrica, usate per preparare zuppe, stufati e brodi con il minimo sforzo e la massima durata, a una temperatura che raggiunge i 96-98 \u00b0C. L\u2019unica accortezza \u00e8 quella di aggiungere aromi e spezie solo a cottura quasi ultimata, per conservarne le note pi\u00f9 vivaci. Questo metodo per cuocere i cibi consente un minore apporto di grassi estraendo dalla carne e dalle verdure i loro stessi liquidi, e il pesante coperchio ne impedisce l\u2019evaporazione. Vediamo gli ingredienti della nostra ricetta di oggi:<\/p>\n<p>un cosciotti di agnello di circa 800 grammi<br \/>\n2 arance<br \/>\n2 patate<br \/>\n1\/2 bicchiere di vino bianco<br \/>\n1\/2 bicchiere di acqua<br \/>\nun p\u00f2 di aromi come salvia e rosmarino<br \/>\nSale e Pepe quanto basta<\/p>\n<p>Prendiamo la nostra pentola slow cooking, mettiamo al suo interno prima il cosciotto poi prendiamo le patate lavate e tagliate a pezzi uniformi e le aggiungiamo, poi il succo di 1 arancia, qualche fettina di arancia, l&#8217;acqua , il vino, gli aromi e aggiustiamo di sale e pepe.\u00a0La nostra rivisitazione non prevede il passaggio in padella del cosciotto, ma volendo si pu\u00f2 prima rosolare.\u00a0A questo punto avvieremo la cottura per circa 3 ore- 3 ore e mezzo in base alla grandezza del cosciotto. A fine cottura tagliare il cosciotto a fettine e sistemarlo in un piatto da portata accanto alle patate e a\u00a0qualche fettina di arancia.<\/p>\n<p>Abbinamento: l&#8217;agnello va abbinato con un vino rosso come un Montefalco Sagrantino secco.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dedicheremo qualche settimana al metodo della cottura a bassa temperatura\u00a0utilizzata\u00a0in tempi antichissimi\u00a0per mezzo di\u00a0una fonte di calore naturale e materiali\u00a0come la terracotta.<\/p>\n","protected":false},"author":22,"featured_media":55528,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[34,124],"tags":[],"class_list":["post-55527","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-magazine","category-ricette-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/55527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=55527"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/55527\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/55528"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=55527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=55527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=55527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}