{"id":55540,"date":"2016-04-14T14:27:53","date_gmt":"2016-04-14T12:27:53","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/al-via-gara-valutare-la-progettazione-del-ospedale-cosenza\/"},"modified":"2023-01-17T12:01:43","modified_gmt":"2023-01-17T11:01:43","slug":"86271-al-via-gara-valutare-la-progettazione-del-ospedale-cosenza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/86271-al-via-gara-valutare-la-progettazione-del-ospedale-cosenza\/","title":{"rendered":"Al via gara per valutare la progettazione del nuovo ospedale di Cosenza"},"content":{"rendered":"<p><strong>Avviate le procedure per l\u2019acquisizione dello Studio di fattibilit\u00e0 che porter\u00e0 alla costruzione ex novo dell&#8217;Annunziata.<\/strong><!--more--><br \/>\n&nbsp;<br \/>\nCATANZARO &#8211; La Regione Calabria procede nell&#8217;iter burocratico per la realizzazione del nuovo ospedale di Cosenza. Il Dirigente generale del Dipartimento regionale \u201cInfrastrutture\u201d Domenico Pallaria, comunica, con un nota dell\u2019Ufficio stampa, che \u00e8 stata avviata la procedura per l\u2019acquisizione dello Studio di fattibilit\u00e0 del progetto che porter\u00e0 al completo restyling dell&#8217;Annunziata. In data di ieri, 13\u00a0aprile, \u00e8 stato spedito all\u2019Unione Europea l\u2019avviso, previsto dal vigente Codice dei Contratti Pubblici, contenente il bando GUEE ed oggi stesso sono stati pubblicati sul portale regionale il bando di gara, il disciplinare e la modulistica per la presentazione delle offerte. <strong>Chi si aggiudicher\u00e0 l&#8217;appalto dovr\u00e0 preparare una relazione in cui saranno descritte: le caratteristiche funzionali, tecniche, gestionali, economico-finanziarie dei lavori<\/strong> da realizzare;\u00a0l&#8217;analisi delle possibili alternative rispetto alla soluzione realizzativa individuata;\u00a0la verifica della possibilit\u00e0 di coinvolgere i privati nel progetto;\u00a0l&#8217;analisi dello stato di fatto, nelle sue eventuali componenti architettoniche, geologiche, socio-economiche, amministrative;\u00a0la descrizione, ai fini della valutazione preventiva della sostenibilit\u00e0 ambientale e della compatibilit\u00e0 paesaggistica dell&#8217;intervento, dei requisiti dell&#8217;opera da progettare, delle caratteristiche e dei collegamenti con il contesto nel quale l&#8217;intervento si inserisce, con particolare riferimento alla verifica dei vincoli ambientali, storici, archeologici, paesaggistici interferenti sulle aree o sugli immobili interessati dall&#8217;intervento, nonch\u00e9 l&#8217;individuazione delle misure idonee a salvaguardare la tutela ambientale e i valori culturali e paesaggistici.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avviate le procedure per l\u2019acquisizione dello Studio di fattibilit\u00e0 che porter\u00e0 alla costruzione ex novo dell&#8217;Annunziata.<\/p>\n","protected":false},"author":22,"featured_media":55541,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42,571],"tags":[],"class_list":["post-55540","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/55540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=55540"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/55540\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/55541"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=55540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=55540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=55540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}