{"id":55581,"date":"2016-04-15T13:29:08","date_gmt":"2016-04-15T11:29:08","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/la-vedova-allegra-e-il-prossimo-appuntamento-del-teatro-rendano\/"},"modified":"2023-01-17T12:01:47","modified_gmt":"2023-01-17T11:01:47","slug":"86419-la-vedova-allegra-e-il-prossimo-appuntamento-del-teatro-rendano","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/86419-la-vedova-allegra-e-il-prossimo-appuntamento-del-teatro-rendano\/","title":{"rendered":"&#8216;La Vedova Allegra&#8217; \u00e8 il prossimo appuntamento del Teatro Rendano"},"content":{"rendered":"<p><strong>Il penultimo appuntamento della \u201cStagione teatrale 2015\/2016\u201d, firmato \u201cL&#8217;AltroTeatro\u201d, rende omaggio all&#8217;affascinante mondo dell&#8217;Operetta.<\/strong><!--more--><br \/>\nCOSENZA &#8211; Domani, alle 20.30, e domenica 17 aprile, alle 18,00, sul palco del Teatro Rendano, il capolavoro di Franz Leh\u00e0r <strong>\u201cLa vedova allegra\u201d<\/strong> di e con Umberto Scida ed Elena D&#8217;Angelo.\u00a0Tra tutte le operette \u00e8 la pi\u00f9 rappresentata,\u00a0\u00e8 il simbolo del genere, la punta di diamante di quel mondo patinato e luccicante che non torner\u00e0 mai pi\u00f9: la Belle Epoque. Interpretato da Umberto Scida (Njegus) ed Elena D\u2019Angelo (Hanna Glawary), coppia d\u2019oro dell\u2019operetta in Italia, e con la regia dello stesso Umberto Scida, \u201cLa Vedova Allegra\u201d si conferma come una delle operette pi\u00f9 famose dell\u2019intero repertorio operettistico. All\u2019ambasciata del Pontevedro a Parigi, c\u2019\u00e8 grande fermento. Sta arrivando la Signora Hanna Glawary, giovane vedova del ricchissimo banchiere di corte.<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019ambasciatore, il Barone Zeta, ha ricevuto l\u2019incarico di trovare un marito pontevedrino alla vedova per conservare i milioni di dote della signora, in patria. Infatti se la signora Glawary passasse a seconde nozze con un francese, il suo capitale lascerebbe la Banca Nazionale Pontevedrina e per il Pontevedro sarebbe la rovina. Njegus, cancelliere dell\u2019ambasciata, \u00e8 un po\u2019 troppo pasticcione, ma c\u2019\u00e8 il conte Danilo che potrebbe andare benissimo. Njegus e Zeta tentano di convincerlo, ma lui non ne vuole sapere. Tra Danilo e Hanna c\u2019era stata una storia d\u2019amore finita male a causa della famiglia di Danilo. Da parte sua la vedova, pur amando Danilo, non lo vuole dimostrare e fa di tutto per farlo ingelosire.<\/p>\n<p>&nbsp;<\/p>\n<p>Frattanto si snoda un\u2019altra storia d\u2019amore che vede protagonisti Valencienne, giovane moglie di Zeta, e Camillo de Rossillon, un diplomatico francese che la corteggia con assiduit\u00e0. I due si danno appuntamento\u00a0in un chiosco. Li sta per sorprendere il barone Zeta quando Njegus riesce a fare uscire per tempo Valencienne sostituendola con Hanna. La vedova sorpresa con Camillo! Tutti sono sconvolti, Danilo furioso abbandona la festa. Tutto ormai sembra compromesso, ma Njegus, vero Deus ex-machina, riesce a sciogliere gli equivoci e a far confessare ad Hanna e Danilo il loro reciproco amore. La patria \u00e8 salva. D\u2019ora in poi la signora Glawary non sar\u00e0 pi\u00f9 \u201cLa vedova allegra\u201d, ma la felice consorte del conte Danilo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il penultimo appuntamento della \u201cStagione teatrale 2015\/2016\u201d, firmato \u201cL&#8217;AltroTeatro\u201d, rende omaggio all&#8217;affascinante mondo dell&#8217;Operetta.<\/p>\n","protected":false},"author":22,"featured_media":55582,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[40,34],"tags":[],"class_list":["post-55581","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-spettacolo","category-magazine"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/55581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=55581"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/55581\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/55582"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=55581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=55581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=55581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}