{"id":55802,"date":"2016-04-21T10:18:06","date_gmt":"2016-04-21T08:18:06","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/il-cedro-di-calabria-verso-il-riconoscimento-del-marchio-dop\/"},"modified":"2023-01-17T12:02:12","modified_gmt":"2023-01-17T11:02:12","slug":"87392-il-cedro-di-calabria-verso-il-riconoscimento-del-marchio-dop","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/87392-il-cedro-di-calabria-verso-il-riconoscimento-del-marchio-dop\/","title":{"rendered":"Il cedro di Calabria verso il riconoscimento del marchio DOP"},"content":{"rendered":"<p><strong>Europa e Cina sono le nuove frontiere di chi, attraverso il Consorzio del cedro di Calabria, intende realizzare una nuova filiera tra produttori, industria della trasformazione e circuiti turistici.<\/strong> <!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>CATANZARO &#8211; E&#8217; il presidente del consorzio, Angelo Adduci, a tratteggiare il quadro della situazione. La produzione del cedro in Calabria ha il suo punto di forza nella fascia costiera che da Tortora a Sangineto, sulla costa tirrenica cosentina, costituisce la cosiddetta <strong>&#8220;riviera dei cedri&#8221;<\/strong>. Un striscia di territorio lungo la quale operano circa 300 produttori con oltre 90 ettari coltivati. Qui la coltura, molto sensibile al freddo, trova il suo microclima ideale grazie alla convergenza di correnti d&#8217;aria fredde provenienti dalla collina e di correnti calde portate dal mare che mitigano le prime. Negli anni Trenta del secolo scorso la produzione cedricola raggiunse la sua massima espansione con 80.000 quintali commercializzati. Poi la crisi, determinata da diversi fattori fra cui la cementificazione selvaggia di una delle aree piu&#8217; belle della regione che ha sottratto spazio alle coltivazioni. Ma oggi, assicura Adduci, le condizioni per un rilancio ci sono tutte. Si lavora alacremente a un progetto: la raccolta e la trasformazione del cedro impegna migliaia di persone, dai produttori agli addetti alla trasformazione, fino alla ristorazione, all&#8217;industria cosmetica e a quella farmaceutica.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;Stiamo lavorando &#8211; spiega Angelo Adduci &#8211; alla costruzione di un vero e proprio <strong>percorso del cedro<\/strong>, che avr\u00e0 effetti positivi soprattutto per il turismo. Per questo sono state avviate le procedure per il riconoscimento del marchio di derivazione d&#8217;origine protetta (Dop) e abbiamo proposto alla regione un piano nell&#8217;ambito del Pdr. Fino agli anni Ottanta il cedro era conosciuto solo come frutto candito. Oggi l&#8217;industria alimentare lo utilizza per la produzione di dolci, marmellate e sciroppi&#8221;.\u00a0Il consorzio ha gia&#8217; realizzato a <strong>Santa Maria del Cedro<\/strong>, epicentro dell&#8217;attivit\u00e0 del sodalizio, un centro polivalente con un museo dedicato, un laboratorio del gusto, una cittadella industriale e un centro ricerca con un&#8217;area ristorazione. &#8220;Si tratta &#8211; spiega ancora Adduci &#8211; di un&#8217;attrattiva per i turisti. Stiamo lavorando per coinvolgere la ristorazione e i laboratori di pasticceria realizzando una rete di commercializzazione del prodotto&#8221;. Ma la vera sfida e&#8217; conquistare l&#8217;industria cosmetica e quella farmaceutica. Il cedro \u00e8 impiegato in tutta la gamma cosmetica, dal bagno schiuma agli shampoo. Poi, grazie alle sue proprieta&#8217; mediche, come<strong> antidoto al colesterolo e al diabete<\/strong>, c&#8217;e&#8217; l&#8217;interesse crescente delle industrie farmaceutiche.<\/p>\n<p>&nbsp;<\/p>\n<p>In questo campo, le prospettive all&#8217;estero sono interessanti. &#8220;Abbiamo contatti in tutta Europa, soprattutto con i paesi del Nord, molto interessati ai liquori e ai <strong>cosmetici a base di cedro<\/strong>. Ma il paese pi\u00f9 promettente &#8211; dice Adduci &#8211; \u00e8 la Cina, dove gli agrumi non esistono e dove constatiamo un grande interesse dell&#8217;industria cosmetica. C&#8217;\u00e8 poi l&#8217;interesse di Israele e dei rabbini, che utilizzano l&#8217;agrume nei loro riti religiosi in occasione della festa del Sukkoth. &#8220;In luglio e agosto &#8211; dice il presidente del consorzio del cedro &#8211; almeno un centinaio di rabbini raggiunge le nostre zone per acquistare il frutto, dopo averlo meticolosamente esaminato al fine di accertarne la purezza&#8221;.\u00a0Primo obiettivo dei produttori e&#8217; l&#8217;aumento della produzione, oggi attestata fra i 7.500 e i 15.000 quintali secondo l&#8217;annata. &#8220;Possiamo arrivare a produrre almeno 40.000 quintali all&#8217;anno&#8221; sottolinea Adduci, che parla della possibilita&#8217; di costruire un vero e proprio sistema economico da costruire nel comprensorio. &#8220;Negli anni Novanta il 90% della nostra produzione era commercializzato fuori dai confini calabresi. Vogliamo invertire questa tendenza &#8211; aggiunge &#8211; costruendo un filiera che coinvolga gli alberghi, i ristoranti, i bar e le pasticcerie del comprensorio, investendo i fondi del Psr, il programma di sviluppo agricolo regionale&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Europa e Cina sono le nuove frontiere di chi, attraverso il Consorzio del cedro di Calabria, intende realizzare una nuova filiera tra produttori, industria della trasformazione e circuiti turistici.<\/p>\n","protected":false},"author":22,"featured_media":55803,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[63,34],"tags":[],"class_list":["post-55802","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gusto","category-magazine"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/55802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=55802"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/55802\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/55803"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=55802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=55802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=55802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}