{"id":55900,"date":"2016-04-24T06:30:50","date_gmt":"2016-04-24T04:30:50","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/museo-dei-brettii-di-cosenza-domani-eccezionalmente-aperto\/"},"modified":"2023-01-17T12:02:23","modified_gmt":"2023-01-17T11:02:23","slug":"87764-museo-dei-brettii-di-cosenza-domani-eccezionalmente-aperto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/87764-museo-dei-brettii-di-cosenza-domani-eccezionalmente-aperto\/","title":{"rendered":"Museo dei Brettii di Cosenza domani eccezionalmente aperto"},"content":{"rendered":"<p><strong>In occasione della Festa della Liberazione di domani\u00a0il Museo dei Brettii e degli Enotri sar\u00e0 aperto, dalle 10.00 alle 13.00 e dalle 15.30 alle 18.30.<\/strong><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; \u00a0La Direzione del Museo comunica inoltre che su prenotazione (da effettuare chiamando lo 0984-23303) sar\u00e0 disponibile il servizio di <strong>visita guidata<\/strong>, a cura della Museion srl, la societ\u00e0 concessionaria dei servizi aggiuntivi del Museo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In occasione della Festa della Liberazione di domani\u00a0il Museo dei Brettii e degli Enotri sar\u00e0 aperto, dalle 10.00 alle 13.00 e dalle 15.30 alle 18.30.<\/p>\n","protected":false},"author":22,"featured_media":55901,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[41,34],"tags":[],"class_list":["post-55900","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-intrattenimento","category-magazine"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/55900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=55900"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/55900\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/55901"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=55900"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=55900"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=55900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}