{"id":56100,"date":"2016-04-29T06:33:34","date_gmt":"2016-04-29T04:33:34","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/ndrangheta-ancora-un-sequestro-beni-alle-cosche-33-milioni-euro\/"},"modified":"2023-01-17T12:02:45","modified_gmt":"2023-01-17T11:02:45","slug":"88593-ndrangheta-ancora-un-sequestro-beni-alle-cosche-33-milioni-euro","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/88593-ndrangheta-ancora-un-sequestro-beni-alle-cosche-33-milioni-euro\/","title":{"rendered":"&#8216;Ndrine ed economia, cosca detiene il monopolio sull&#8217;edilizia e il commercio della carne"},"content":{"rendered":"<h4><strong>Posti i sigilli a 33 milioni di euro di beni ritenuti provento di attivit\u00e0 illecite.\u00a0<\/strong><\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>REGGIO CALABRIA &#8211; La Guardia di Finanza sta eseguendo nella provincia reggina un\u00a0provvedimento emesso dalla Sezione Misure di Prevenzione del Tribunale con il\u00a0quale \u00e8 stata disposta, nei confronti di soggetti intranei e contigui alla cosca Labate\u00a0il sequestro del patrimonio aziendale di sei aziende, 97 immobili, sei\u00a0veicoli e diversi rapporti finanziari e assicurativi, il tutto per un valore\u00a0stimato pari a circa 33 milioni di euro.\u00a0L\u2019esistenza e l\u2019operativit\u00e0 del clan Labate nella zona sud di Reggio Calabria\u00a0e, in particolare, nei quartieri Gebbione e Sbarre, \u00e8 stata pi\u00f9 volte acclarata con\u00a0pi\u00f9 di una pronuncia gi\u00e0 passata in giudicato. Nello specifico, l&#8217;organizzazione criminale\u00a0aveva il controllo assoluto della gestione delle attivit\u00e0\u00a0economiche, con particolare riferimento al settore del commercio della carne,\u00a0oltre che a quello dell\u2019edilizia e del movimento terra.\u00a0A seguito di una mirata attivit\u00e0 di indagine e di analisi economico-finanziarie,\u00a0gli uomini della Guardia di Finanza hanno accertato che <strong>tutti gli investimenti\u00a0dei soggetti colpiti dal provvedimento e dei componenti dei loro nuclei familiari\u00a0sono stati effettuati con denaro di provenienza delittuosa<\/strong> in quanto derivante da\u00a0attivit\u00e0 imprenditoriale svolta secondo modalit\u00e0 mafiose. Infatti, il potere\u00a0mafioso della cosca Labate veniva sfruttato per sbaragliare la concorrenza, per\u00a0imporsi sul mercato, per procurarsi clienti, con totale alterazione delle regole\u00a0della concorrenza, finendo per operare nella zona di competenza in posizione\u00a0sostanzialmente monopolistica.\u00a0I dettagli dell\u2019operazione saranno resi noti nel corso di una conferenza stampa\u00a0che si terr\u00e0 alle ore 11,00 presso il Comando Provinciale della Guardia di\u00a0Finanza di Reggio Calabria alla presenza del Procuratore Aggiunto della\u00a0Procura della Repubblica di Reggio Calabria, Calogero Gaetano Paci.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Posti i sigilli a 33 milioni di euro di beni ritenuti provento di attivit\u00e0 illecite.\u00a0<\/p>\n","protected":false},"author":22,"featured_media":56101,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,571],"tags":[],"class_list":["post-56100","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/56100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=56100"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/56100\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/56101"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=56100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=56100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=56100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}