{"id":56148,"date":"2016-04-30T07:20:41","date_gmt":"2016-04-30T05:20:41","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/tasse-rende-esenzioni-centro-storico-abitazioni-principali\/"},"modified":"2023-01-17T12:02:50","modified_gmt":"2023-01-17T11:02:50","slug":"88738-tasse-rende-esenzioni-centro-storico-abitazioni-principali","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/88738-tasse-rende-esenzioni-centro-storico-abitazioni-principali\/","title":{"rendered":"Tasse a Rende: esenzioni per il centro storico e abitazioni principali"},"content":{"rendered":"<p><strong>Approvate in consiglio comunale le nuove aliquote Imu, Tasi e Tari per il 2016.<\/strong><\/p>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>RENDE (CS) \u2013 Nuova tassazione per i rendesi. Sono state approvate ieri in consiglio comunale, con voto contrario di tutti i consiglieri di minoranza, le nuove aliquote da applicare per tassare i cittadini d\u2019Oltrecampagnano. Stabilita la IUC (Imposta Unica Comunale) che comprende Imu, Tasi e Tari. Le novit\u00e0 pi\u00f9 rilevanti riguardano le attivit\u00e0 commerciali e le abitazioni dei nuovi residenti del centro storico di Rende. Previsto, invece, un aggravio dei costi sui rifiuti derivante dal nuovo appalto che dovr\u00e0 essere affidato per l\u2019avvio della raccolta differenziata porta a porta. Nonostante ci\u00f2 si prevede che il \u2018nuovo corso\u2019 dello smaltimento rifiuti a Rende comporter\u00e0 un risparmio di circa 800mila euro. Attualmente, con Calabra Maceri, se ne spendono circa 9 milioni. <strong>Da evidenziare che, ad oggi sulle casse del Comune di Rende gravano 27 milioni di euro di tributi non riscossi<\/strong> a fronte del recupero nello scorso anno di 257mila euro di tributi evasi. I fabbricati industriali invece pagano una Tari di migliaia di euro superiore rispetto ai Comuni del circondario. E\u2019 per\u00f2 possibile usufruire di riduzioni ed esenzioni da Tari, Tasi o Imu presentando apposita richiesta agli uffici competenti.<\/p>\n<h2>TARI<\/h2>\n<p>La tassazione si basa sui costi di gestione del servizio smaltimento rifiuti che dovranno essere interamente coperti con i tributi versati dai cittadini. Costi che saranno spalmati sulle 51mila utenze domestiche e non domestiche presenti sul territorio di competenza. Previa opportuna richiesta sar\u00e0 possibile godere di alcuni sgravi sul pagamento della tassa. Sono infatti previste riduzioni per anziani o disabili proprietari di immobili, ma di fatto residenti in strutture sanitarie; nella misura del 40% per le aziende che assumono disoccupati attraverso il progetto Garanzia Giovani e di 2\/3 per gli italiani residenti all\u2019estero in pensione. \u00a0I coltivatori diretti, gli imprenditori agricoli e <strong>gli utenti che provvederanno al compostaggio dei rifiuti organici in casa producendo autonomamente compost da usare nei propri orti o giardini godranno di uno sconto del 15%<\/strong> sulla quota variabile della Tari.<\/p>\n<p>&nbsp;<\/p>\n<p>Riduzione del 60% dell\u2019importo totale per gli utenti i quali dispongono di un punto di raccolta dei rifiuti distante dalla propria abitazione\/attivit\u00e0 superiore ai 400 metri. Esenti nullatenenti, persone in carico ai servizi sociali o che vertano in particolari condizioni di disagio. Contemplate tra le utenze esenti anche quelle dei residenti in contrada Coda di Volpe nei pressi del depuratore consortile e dell\u2019ex inceneritore.<strong> Nessuna agevolazione, nonostante le esplicite richieste da parte dei cittadini, per le abitazioni a ridosso dell\u2019ex Legnochimica in contrada Lecco.<\/strong> Esenzioni dal pagamento, al fine di scongiurare lo spopolamento, anche per le attivit\u00e0 commerciali e i nuovi residenti del centro storico.<\/p>\n<p>&nbsp;<\/p>\n<h2>TASI<\/h2>\n<p>Imposta sui fabbricati di propriet\u00e0. Escluse dalla tassazione le abitazioni principali, prima casa, che non rientrano nelle categorie definite di lusso (A1, A8, A9) e le aree edificabili. Sono tassabili le pertinenze che rientrano nelle categorie catastali: C2 (magazzini e locali di deposito come cantine e solai), C6 (stalle e scuderie, garage) e C7 (tettoie chiuse o aperte) e i terreni di coltivatori diretti ed imprenditori agricoli.<strong> Gli inquilini che usano l\u2019immobile in fitto come abitazione principale in cui risiedono saranno esentati dal pagamento del 30% di Tasi<\/strong> mentre il proprietario sar\u00f2 assoggettato al rimanente 70%. Nel caso in cui i componenti del nucleo familiare abbiano trasferito la residenza anagrafica in altri immobili del territorio comunale si considera abitazione principale un solo immobile per nucleo familiare. L\u2019aliquota approvata dal Consiglio comunale riunitosi ieri \u00e8 dello 0,8 per mille. Si \u00e8 scelto di non applicare il massimo del 2,5%.<\/p>\n<p>&nbsp;<\/p>\n<p>Sono esenti i nullatenenti, le persone in carico ai servizi sociali o che vertano in particolari condizioni di disagio. Base imponibile ridotta del 50% per i fabbricati dichiarati inagibili, inabitabili, di interesse storico o artistico. Riduzioni per anziani o disabili proprietari di immobili, ma di fatto residenti in strutture sanitarie; nella misura del 50% per gli immobili concessi in comodato a parenti diretti che la usino come abitazione principale e di 2\/3 per gli italiani residenti all\u2019estero in pensione. <strong>Tributo ridotto del 75% per fabbricati locati a canone concordato.<\/strong> Il pagamento avviene in due rate con scadenza al 16 giugno e 16 dicembre.<\/p>\n<p>&nbsp;<\/p>\n<h2>IMU<\/h2>\n<p>Sono escluse dalla tassazione le abitazioni principali che non rientrano nelle categorie definite di lusso (A1, A8, A9) e le loro pertinenze. <strong>Esenti anche gli immobili in cui vive il coniuge a seguito di separazione,<\/strong> i fabbricati rurali, i fabbricati destinati alla vendita, gli anziani o disabili proprietari di immobili, ma di fatto residenti in strutture sanitarie e gli italiani residenti all\u2019estero in pensione. Il valore dell\u2019imposta \u00e8 stabilito nella misura del 5% della rendita catastale. Per i fabbricati dichiarati inagibili, inabitabili, di interesse storico o artistico e per gli immobili concessi in comodato a parenti diretti che la usino come abitazione principale la base imponibile viene ridotta del 50%. La tassazione \u00e8 ridotta del 75% per i fabbricati locati a canone concordato. Il pagamento pu\u00f2 avvenire in due rate con scadenza al 16 giugno e 16 dicembre o in un\u2019unica soluzione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Approvate in consiglio comunale le nuove aliquote Imu, Tasi e Tari per il 2016.<\/p>\n","protected":false},"author":18,"featured_media":56149,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,571,44],"tags":[],"class_list":["post-56148","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-in-evidenza","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/56148","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=56148"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/56148\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/56149"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=56148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=56148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=56148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}