{"id":56238,"date":"2016-05-03T09:55:07","date_gmt":"2016-05-03T07:55:07","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/premio-san-francesco-paola-un-esempio-imitare-tutti-cosentini\/"},"modified":"2023-01-17T12:03:00","modified_gmt":"2023-01-17T11:03:00","slug":"89169-premio-san-francesco-paola-un-esempio-imitare-tutti-cosentini","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/89169-premio-san-francesco-paola-un-esempio-imitare-tutti-cosentini\/","title":{"rendered":"Premio San Francesco di Paola, un esempio da imitare per tutti i cosentini"},"content":{"rendered":"<p><strong>Il giornalista Michele Cucuzza a Paola per premiare personalit\u00e0 che si sono distinte grazie alle loro attivit\u00e0 professionali.\u00a0<\/strong><\/p>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<div class=\"messageheaders\">\n<p><span class=\"rightSubject\"><span class=\"date\">PAOLA (CS) &#8211;\u00a0<\/span><\/span>San Francesco di Paola e la riscoperta dei nostri valori. Si terr\u00e0 Venerd\u00ec 6 Maggio alle 20.30 presso il teatro Odeon di Paola il premio San Francesco di Paola 2016. Un evento per promuovere la cultura morale che ci appartiene, riscoprire\u00a0un&#8217;icona che \u00e8\u00a0modello della tradizione attualizzandola alla nostra identit\u00e0 storica pi\u00f9 alta. Ricchezza e storia del nostro territorio riconosciute in tutto il mondo:\u00a0a Parigi San Francesco \u00e8 il co-patrono, Picasso di secondo nome si chiamava Francisco de Paula, a Napoli di fronte al palazzo reale e Roma a Trinit\u00e0 dei Monti gli dedicano le chiese pi\u00f9 belle. <strong>Un uomo, un santo, un modello da imitare a cui \u00e8 ispirato il premio che verr\u00e0 consegnato a cinque persone che si sono particolarmente distinte nelle proprie attivit\u00e0:<\/strong> Eugenio Facciolla procuratore capo della Procura di Castrovillari, Monsignor Francesco Nol\u00e8 arcivescovo della diocesi Cosenza &#8211; Bisignano, cosimo Maria Ferri sottosegretario alla giustizia, Mario Oliverio governatore della Regione Calabria e Roberto Bilotti Ruggi d&#8217;Aragona presidente del Museo Bilotti &#8211; Roma. Grazie a Roberto Bilotti la figura di San Francesco \u00e8 stata valorizzata con tre grandi mostre esposte sul territorio dal\u00a02012 ad oggi che rendono la figura del nostro Santo viva ed attuale. Questa una delle ragioni che hanno spinto la &#8220;Commissione per le celebrazioni del seicentenario&#8221; a conferire il premio San Francesco di Paola a\u00a0<span style=\"color: #000000;\">Roberto Bilotti della nota famiglia di mecenati\u00a0ch<\/span><span style=\"color: #000000;\">e\u00a0tanto ha \u00a0fatto\u00a0per la nostra Citt\u00e0. <\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\">Ricordiamo, in particolare, il\u00a0<\/span><span style=\"color: #000000;\">Mab museo all&#8217;aperto, repertorio di sculture di\u00a0artisti\u00a0noti internazionalmente su corso Mazzini;\u00a0la <\/span><span style=\"color: #000000;\">chiesa di San Nicola arricchite dalla donazione di dieci opere monumentali dal cinquecento al contemporaneo; <strong>l&#8217;<\/strong><\/span><strong>Oasi francescana\u00a0 costruita su terreno edificatorio donato dalla famiglia Bilotti<\/strong>;<strong>\u00a0in altre citt\u00e0\u00a0la\u00a0Fondazione\u00a0Lisa Bilotti\u00a0promuove ogni anno un progetto di ricerca avanzata sulle leucemie<\/strong> presso il Memorial Sloan Kettering Cancer Center di New York; il\u00a0laboratorio del trapianto del midollo osseo<strong>\u00a0<\/strong>\u201cLisa Bilotti\u201d nello stesso ospedale; oltre a sostenere la &#8220;Fondazione esprimi un desiderio&#8221; per bambini malati terminali; e l&#8217;ospedale Ruggi d&#8217;Aragona di Salerno. Roberto Bilotti\u00a0ha donato\u00a0personalmente al Comune di Rende\u00a0le sue collezioni con le quali sono stati costituiti il\u00a0 Museo Arte Contemporanea nel castello di Rende, unico in Calabria con una collezione permanente; il\u00a0Museo ceramica di Calabria, nell&#8217;ex ristorante Pantagruel; oltre una collezione di 60 opere dei futuristi calabresi, in prima linea nel movimento all&#8217;avanguardia in Europa,\u00a0che saranno esposte in permanenza al Museo del Presente. Un importante polo con\u00a0la stanza dei disegni futuristi di Boccioni della collezione Carlo Bilotti alla\u00a0Galleria Nazionale di palazzo Arnone.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Roberto Bilotti ha donato il bronzo di Boccioni &#8220;Forme Uniche nella continuit\u00e0 nello spazio&#8221; riportata sui 20 centesimi insieme ad altre\u00a0sculture di de Chirico, Consagra, Greco, Rotella. <strong>Con\u00a0Irene Telesio ultima ed erede della sua famiglia depositaria di mille anni di storia di questa citt\u00e0 ha costituito con donazioni\u00a0a\u00a0Casa delle Culture a Cosenza\u00a0il museo con le memorie del territorio recuperando l&#8217;identit\u00e0 storica dei cittadini.<\/strong>\u00a0Ha portato capolavori in mostra a Cosenza, tra le quali ricordiamo: nel\u00a02005 \u201cDa Picasso a Warhol opere dalla collezione Bilotti\u201d al complesso monumentale Sant&#8217;Agostino;\u00a0nel 2011\u00a0 Cosenza Postunitaria, memorie della Calabria garibaldina, unitaria e postunitaria;\u00a0 &#8220;Il Divino nell\u2019Arte Contemporanea\u201d con Vittorio Sgarbi al complesso Sant&#8217;Agostino,\u00a0\u201cDiaspora nella Terra dei Bruzi\u201d mostra temporanea di sculture di grandi artisti americani all&#8217;interno del Mab.\u00a0Nel 2012\u00a0 in occasione del &#8220;Cinquecentenario della proclamazione a patrono della Calabria\u201d a palazzo dei Bruzi sono stati esposti capolavori di Brill, Ribera detto lo Spagnoletto, Coppola, Finoglio, Mellan, Giordano, Salfi fino al pop\u00a0Rotella. Una \u00a0grande mostra curata da Roberto Bilotti voluta dall&#8217;allora sindaco Mario Occhiuto devoto francescano e attento al recupero e\u00a0alla valorizzazione delle nostre tradizioni.<\/p>\n<p>&nbsp;<\/p>\n<p>Nel\u00a02014\u00a0a palazzo Arnone<strong>\u00a0<\/strong>le opere insieme a importanti reliquie sono state esposte e tutt&#8217;oggi sono visitabili nelle sale di piano terra. Quest&#8217;anno Mario Occhiuto e Graziano di Natale, presidente della Commissione per le celebrazioni del seicentenario,\u00a0hanno voluto una grande mostra in chiave contemporanea\u00a0per avvicinare il nostro Santo ai giovani con un linguaggio espresso da\u00a0una ricerca sulla realt\u00e0 del nostro tempo. Cos\u00ec Roberto <strong>Bilotti curatore della mostra che ha base a palazzo della Provincia, di cui una sezione \u00e8 itinerante nei paesi della Calabria dove San Francesco ha operato, ha\u00a0\u00a0coinvolto 50\u00a0artisti contemporanei, tra i pi\u00f9 noti in Italia.<\/strong> Essi hanno realizzate opere iconografiche e rievocative dell&#8217;operato francescano, dono artisti con riconoscimenti istituzionali,\u00a0diversi\u00a0di loro gi\u00e0 selezionati da Commissioni ministeriali per grandi committenze\u00a0quali Roberto Ferri che ha realizzato la via crucis per la ricostruita cattedrale di Noto, Giovanni Gasparro con le grandi pale\u00a0per l&#8217;Aquila, Giuseppe Ducrot autore la statua di Sant&#8217;Annibale\u00a0a San Pietro in Vaticano, delle cornucopie al Museo Borghese, al San Benedetto all&#8217;Abbazia di Monte Cassino;\u00a0Giuseppe Gallo con opere nella chiesa di Santa Maria degli Angeli e musei internazionali. La mostra \u00e8 in progress si arricchisce con altre opere aggiuntive.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<div id=\"messagebody\">\n<div class=\"message-htmlpart\">\n<div class=\"rcmBody\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-89208 aligncenter\" src=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2016\/05\/premio-san-francesco-440x221.jpg\" alt=\"premio-san-francesco\" width=\"440\" height=\"221\" title=\"\"><\/p>\n<div dir=\"ltr\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Il giornalista Michele Cucuzza a Paola per premiare personalit\u00e0 che si sono distinte grazie alle loro attivit\u00e0 professionali.\u00a0<\/p>\n","protected":false},"author":22,"featured_media":56239,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[40,571,34],"tags":[],"class_list":["post-56238","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-spettacolo","category-in-evidenza","category-magazine"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/56238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=56238"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/56238\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/56239"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=56238"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=56238"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=56238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}