{"id":56310,"date":"2016-05-05T04:00:02","date_gmt":"2016-05-05T02:00:02","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/soveria-mannelli-marzi-ferrovia-interrotta-6-anni-governo-intervenga\/"},"modified":"2023-01-17T12:03:09","modified_gmt":"2023-01-17T11:03:09","slug":"89459-soveria-mannelli-marzi-ferrovia-interrotta-6-anni-governo-intervenga","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/89459-soveria-mannelli-marzi-ferrovia-interrotta-6-anni-governo-intervenga\/","title":{"rendered":"\u201cSoveria Mannelli-Marzi, ferrovia interrotta da 6 anni. Il governo intervenga\u201d"},"content":{"rendered":"<p><strong>Il deputato del Movimento 5 Stelle Paolo Parentela ha interrogato sulla vicenda i ministri dell\u2019economia e dei trasporti.<\/strong><!--more--><br \/>\n&nbsp;<\/p>\n<p>COSENZA \u2013 Il Movimento 5 Stelle, attraverso il suo deputato <strong>Paolo Parentela<\/strong>, ha interrogato i ministri dell\u2019economia e dei trasporti in merito alla situazione della tratta ferroviaria che unisce <strong>Catanzaro e Cosenza<\/strong>. Il pentastellato ha chiesto al governo e alla Regione Calabria di provvedere urgentemente alla messa in sicurezza dei <strong>31 chilometri di strada ferrata<\/strong> tra <strong>Soveria Mannelli<\/strong>, in provincia di Catanzaro, e <strong>Marzi<\/strong>, nel cosentino.<br \/>\n&nbsp;<\/p>\n<p>\u201cAi cittadini calabresi \u2013 afferma Parentela \u2013 devono essere garantiti i medesimi diritti di accesso ai trasporti di cui godono i cittadini di altre regioni italiane. Lo spopolamento delle aree interne della Calabria ed il conseguente crollo economico sono dovuti anche alla mancanza di infrastrutture ferroviarie adeguate. I 31 km di strada ferrata tra Soveria Mannelli e Marzi \u00e8 interrotta da sei anni a causa di una frana e nulla \u00e8 stato fatto per ripristinarla. <strong>\u00c8 grave, soprattutto se si considera che buona parte degli smottamenti che ne hanno causato l\u2019inagibilit\u00e0, sono di lieve entit\u00e0<\/strong>. Basta dunque un piccolo sforzo per restituire ai cittadini ed al territorio un servizio fondamentale\u201d.<br \/>\n&nbsp;<\/p>\n<p>\u201cNel \u2018Patto per la Calabria\u2019 \u2013 conclude Parentela \u2013 <strong>recentemente sottoscritto da Renzi ed Oliverio, neanche un centesimo viene destinato per rilanciare adeguatamente le vie di comunicazione tra i principali centri calabresi e l\u2019entroterra<\/strong>. Bisogna dimostrare la volont\u00e0 politica di rilanciare l\u2019economia della aree interne della Calabria investendo sulla manutenzione delle infrastrutture viarie gi\u00e0 presenti. Non servono annunci spot, ma soluzioni concrete per il territorio\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il deputato del Movimento 5 Stelle Paolo Parentela ha interrogato sulla vicenda i ministri dell\u2019economia e dei trasporti.<\/p>\n","protected":false},"author":22,"featured_media":56311,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,571],"tags":[],"class_list":["post-56310","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/56310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=56310"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/56310\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/56311"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=56310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=56310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=56310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}