{"id":56353,"date":"2016-05-05T10:51:52","date_gmt":"2016-05-05T08:51:52","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/ponte-calatrava-rifiuti-pericolosi-riva-al-crati-tre-imputati\/"},"modified":"2023-01-17T12:03:14","modified_gmt":"2023-01-17T11:03:14","slug":"89615-ponte-calatrava-rifiuti-pericolosi-riva-al-crati-tre-imputati","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/89615-ponte-calatrava-rifiuti-pericolosi-riva-al-crati-tre-imputati\/","title":{"rendered":"Ponte di Calatrava e rifiuti pericolosi in riva al Crati, tre imputati"},"content":{"rendered":"<p><strong>Rinviati a giudizio un dirigente comunale, il direttore dei lavori e l&#8217;amministratore delegato della ditta aggiudicataria dell&#8217;appalto.<\/strong><\/p>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Il nuovo ecomostro cosentino continua a far discutere. Tre persone sono state ieri rinviate a giudizio per la procedura di affidamento dei lavori del ponte di Calatrava voluto dall&#8217;ex sindaco di Cosenza Mario Occhiuto e dall&#8217;ex vicesindaco Katya Gentile. <strong>Fu proprio la Gentile dopo la sua cacciata a far avviare le indagini in merito alla bonifica dell&#8217;area che sarebbe dovuta avvenire, secondo l&#8217;accusa, prima di chiudere la gara d&#8217;appalto<\/strong>. Il ponte progettato dal noto architetto spagnolo, pi\u00f9 volte citato in giudizio dai Comuni in cui ha realizzato le proprie opere, collegher\u00e0 le due sponde del fiume Crati dal quartiere Gergeri a via Reggio Calabria. Lungo 140 metri ed alto 88, il serpentone di calcestruzzo si inserisce con violenza nella cornice di uno degli scorci pi\u00f9 belli della citt\u00e0 che ha come sfondo il centro storico. Per affidarne in fretta e furia la costruzione alla Cimolai nel 2008, secondo quanto emerso dagli atti redatti dalla Procura di Cosenza, si sarebbe &#8216;chiuso un occhio&#8217; sulla bonifica delle rive del fiume che in quel momento presentavano cumuli di rifiuti pericolosi, rifiuti non pericolosi ed ingombranti. Rifiuti che ufficialmente sarebbero stati rimossi solo poco prima dell&#8217;inizio delle trivellazioni necessarie per avviare l&#8217;opera.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Una querelle che ha portato ieri al<strong> rinvio a giudizio di Carlo Pecoraro\u00a0dirigente del settore infrastrutture del Comune di Cosenza, del direttore dei lavori Vito Avino e dell&#8217;allora amministratore delegato della Cimolai Salvatore De Luna.<\/strong> Pecoraro dovr\u00e0 rispondere del reato di abuso d&#8217;ufficio per aver affidato, secondo l&#8217;accusa, i lavori alla Cimolai di Pordenone e all&#8217;impresa che avrebbe svolto la famigerata bonifica, attraverso procedure non conformi alla legge. Anche se di fatto la Cimolai non si occupa di smaltire rifiuti pare che la Procura di Cosenza abbia rilevato come Pecoraro affid\u00f2 loro l&#8217;incarico per un importo pari a 500mila euro. A braccetto con il dirigente comunale alla sbarra i due ingegneri De Luna e Avino sono invece accusati di falso in atto pubblico. In questo caso sotto i riflettori della magistratura sono finiti due verbali che sarebbero stati redatti dai due nel 2008 prima dell&#8217;inizio dei lavori. Verbali in cui si attestava che in quel momento non vi era alcun impedimento per l&#8217;apertura del cantiere. Per la Procura per\u00f2 sarebbe stato necessario procedere alla bonifica prima di far arrivare lungo il Crati ruspe e trivelle. Secondo la tesi della difesa per\u00f2 durante i due sopralluoghi incriminati i cumuli di rifiuti non erano n\u00e9 visibili n\u00e9 rilevanti. Nel frattempo i lavori procedono lungo le sponde del Crati procedono a ritmo serrato.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rinviati a giudizio un dirigente comunale, il direttore dei lavori e l&#8217;amministratore delegato della ditta aggiudicataria dell&#8217;appalto.<\/p>\n","protected":false},"author":18,"featured_media":56354,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42,571],"tags":[],"class_list":["post-56353","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/56353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=56353"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/56353\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/56354"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=56353"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=56353"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=56353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}