{"id":5650,"date":"2012-10-15T05:36:50","date_gmt":"2012-10-15T03:36:50","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=5650"},"modified":"2023-01-17T13:38:56","modified_gmt":"2023-01-17T12:38:56","slug":"2127-manifestazione-sulla-mobilita-elettrica","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/2127-manifestazione-sulla-mobilita-elettrica\/","title":{"rendered":"Manifestazione sulla mobilit\u00e0 elettrica"},"content":{"rendered":"<p style=\"text-align: justify;\">COSENZA &#8211; Sbarca a Cosenza il futuro: il trasporto a zero emissioni.&nbsp;L\u2019Assessorato alla Sostenibilit\u00e0 Ambientale, guidato da Martina Hauser, promuove \u201ce-Drive\u201d,<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">una manifestazione sulla mobilit\u00e0 elettrica articolata in due giornate, il 19 e 20 ottobre, dalle 16 alle 20, su Corso Mazzini. I pi\u00f9 moderni e tecnologici mezzi elettrici, dalle auto ai pi\u00f9 avanzati modelli di bici a pedalata assistita, saranno esposti e a disposizione per dimostrazioni nel capoluogo bruzio.<\/p>\n<p style=\"text-align: justify;\">La manifestazione \u201ce-Drive\u201d si pone come opportunit\u00e0 di informazione, confronto e approfondimento sulla green economy e sul ruolo della pubblica amministrazione nella scelta di una strategia di mobilit\u00e0 urbana sostenibile che riduca l\u2019impatto ambientale e promuova l\u2019utilizzo di tecnologie di trasporto a zero emissioni.<br \/>\u00abL\u2019obiettivo della manifestazione &#8211; spiega l\u2019Assessore Hauser &#8211; \u00e8 incentivare la sostenibilit\u00e0 nel settore dei trasporti attraverso iniziative di promozione della mobilit\u00e0 elettrica e sensibilizzare i cittadini attraverso uno spazio dedicato ai veicoli elettrici\u00bb.<br \/>Molte saranno le aziende automobilistiche e concessionarie coinvolte che esporranno un mezzo elettrico, o un prototipo della propria gamma, dando la possibilit\u00e0 a utenti privati e pubblici di effettuare un test-drive per poterne valutare concretamente i benefici.<br \/>\u201ce-Drive\u201d si inserisce tra le iniziative dell\u2019Assessorato all\u2019Ambiente volte a promuovere le buone pratiche per il miglioramento della qualit\u00e0 dell\u2019aria, la riduzione delle emissioni, dell\u2019inquinamento sonoro e del consumo di energia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Sbarca a Cosenza il futuro: il trasporto a zero emissioni.&nbsp;L\u2019Assessorato alla Sostenibilit\u00e0 Ambientale, guidato da Martina Hauser, promuove \u201ce-Drive\u201d,<\/p>\n","protected":false},"author":22,"featured_media":5651,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42,5],"tags":[],"class_list":["post-5650","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza","category-old"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/5650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=5650"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/5650\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/5651"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=5650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=5650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=5650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}