{"id":56537,"date":"2016-05-09T16:07:37","date_gmt":"2016-05-09T14:07:37","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/detenzione-spaccio-droga-arrestato-un-uomo-nel-cosentino\/"},"modified":"2023-01-17T12:03:35","modified_gmt":"2023-01-17T11:03:35","slug":"90517-detenzione-spaccio-droga-arrestato-un-uomo-nel-cosentino","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/90517-detenzione-spaccio-droga-arrestato-un-uomo-nel-cosentino\/","title":{"rendered":"Detenzione e spaccio di droga, arrestato un uomo nel cosentino"},"content":{"rendered":"<p><strong>I carabinieri hanno sequestrato nell\u2019abitazione di un 44enne di Serra Pedace due chilogrammi di sostanza stupefacente.<\/strong><!--more--><br \/>\n&nbsp;<\/p>\n<p>SPEZZANO SILA (CS) \u2013 I carabinieri della Stazione di Spezzano della Sila unitamente all\u2019Aliquota Operativa della Compagnia Carabinieri di Cosenza hanno tratto in arresto Giovanni Belli, 44enne, di <strong>Serra Pedace<\/strong>, noto alle Forze dell\u2019Ordine, nella flagranza del reato di detenzione ai fini di spaccio di sostanze stupefacenti.<br \/>\n&nbsp;<\/p>\n<p>L\u2019uomo, nella prima mattinata, \u00e8 stato fermato a <strong>Spezzano Piccolo<\/strong> mentre era alla guida della propria automobile nel corso di un predisposto posto di controllo.<br \/>\n&nbsp;<\/p>\n<p>Vedendolo nervoso e conoscendo i suoi precedenti in materia di sostanze stupefacenti, i militari lo hanno sottoposto a perquisizione personale e veicolare rinvenendo, all\u2019interno di un pacchetto di sigarette, due \u2018spinelli\u2019 nonch\u00e9 nel portafoglio la somma contante di <strong>855,00 euro<\/strong> in banconote di piccolo taglio.\u00a0Subito dopo i carabinieri hanno raggiunto l\u2019abitazione dell\u2019uomo rinvenendo in un intercapedine creato appositamente nei gradini della scale, <strong>2 chilogrammi di sostanza stupefacente<\/strong> del tipo \u2018marijuana\u2019 rispettivamente confezionati in un \u2018pane\u201d da un chilo avvolto in un cellophane e, il rimanente, in nove bustine per alimenti pronte alla vendita. Inoltre sono state rinvenute cinque piantine di marijuana di piccole dimensioni.<br \/>\nLa droga \u00e8 stata sottoposta a sequestro unitamente alla somma di denaro trovata ritenuta provento dell\u2019attivit\u00e0 illecita di spaccio mentre l\u2019arrestato, al termine delle formalit\u00e0 di rito, \u00e8 stato associato presso la <strong>casa Circondariale di Cosenza<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I carabinieri hanno sequestrato nell\u2019abitazione di un 44enne di Serra Pedace due chilogrammi di sostanza stupefacente.<\/p>\n","protected":false},"author":22,"featured_media":56538,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[571,28],"tags":[],"class_list":["post-56537","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/56537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=56537"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/56537\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/56538"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=56537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=56537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=56537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}