{"id":56557,"date":"2016-05-10T09:19:45","date_gmt":"2016-05-10T07:19:45","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/incidente-mortale-sulla3-falerna-lamezia-vittima-un-uomo-47-anni\/"},"modified":"2023-01-17T12:03:38","modified_gmt":"2023-01-17T11:03:38","slug":"90607-incidente-mortale-sulla3-falerna-lamezia-vittima-un-uomo-47-anni","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/90607-incidente-mortale-sulla3-falerna-lamezia-vittima-un-uomo-47-anni\/","title":{"rendered":"Incidente mortale sull&#8217;A3 tra Falerna e Lamezia, vittima un uomo di 47 anni"},"content":{"rendered":"<p><strong>I rilievi sul luogo dell&#8217;incidente sono stati effettuati dalla Polizia stradale.<\/strong><\/p>\n<p><!--more--><\/p>\n<p>LAMEZIA TERME &#8211; Si chiamava <strong>Ferdinando Pedone,<\/strong> di 47 anni, la vittima di un incidente stradale accaduto la scorsa notte lungo l&#8217;Autostrada A3, tra gli <strong>svincoli di Falerna e Lamezia Terme<\/strong>. Pedone, che era di Lamezia, era alla guida della sua Mini Cooper e stava procedendo in direzione sud quando, per cause in corso d&#8217;accertamento, ha perso il controllo della vettura ed \u00e9 finito contro la barriera di protezione.<\/p>\n<p>L&#8217;uomo, a causa dell&#8217;urto,\u00a0\u00e8\u00a0 stato sbalzato fuori dall&#8217;abitacolo e, dopo essere finito sull&#8217;asfalto, \u00e8\u00a0stato investito da un <strong>Renault Megane<\/strong> che poi, a sua volta, si \u00e8 scontrata con un autoarticolato. Il conducente della &#8220;Megane&#8221; ha riportato ferite per le quali \u00e8\u00a0stato ricoverato con prognosi riservata nell&#8217;ospedale &#8220;<strong>Pugliese<\/strong>&#8221; di Catanzaro.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-90618 aligncenter\" src=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2016\/05\/Incidente-mortale-Lamezia.jpg\" alt=\"Incidente mortale Lamezia\" width=\"415\" height=\"636\" title=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>I rilievi sul luogo dell&#8217;incidente sono stati effettuati dalla Polizia stradale.<\/p>\n","protected":false},"author":22,"featured_media":56558,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,571],"tags":[],"class_list":["post-56557","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/56557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=56557"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/56557\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/56558"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=56557"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=56557"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=56557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}