{"id":56720,"date":"2016-05-13T14:38:38","date_gmt":"2016-05-13T12:38:38","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/anziano-malmenato-rapinato-casa-nel-centro-storico-cosenza\/"},"modified":"2023-01-17T12:03:57","modified_gmt":"2023-01-17T11:03:57","slug":"91155-anziano-malmenato-rapinato-casa-nel-centro-storico-cosenza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/91155-anziano-malmenato-rapinato-casa-nel-centro-storico-cosenza\/","title":{"rendered":"Anziano malmenato e rapinato in casa nel centro storico di Cosenza"},"content":{"rendered":"<p><strong>La vittima \u00e8 un uomo di 78 anni. Rubati 800 euro e quattro orologi.<\/strong><!--more--><br \/>\n&nbsp;<\/p>\n<p>COSENZA \u2013 <strong>Sono entrati nella sua abitazione in piena notte e lo hanno aggredito e malmenato<\/strong>. Vittima della vicenda un anziano di 78 anni che abita da solo nel centro storico di Cosenza. Alcuni sconosciuti sono riusciti ad entrare nel suo appartamento e dopo averlo picchiato, si sono impossessati di circa 800 euro e di quattro orologi. <strong>Una volta fuggiti il 78enne ha avvisato la polizia che ha subito avviato le indagini per risalire agli autori della rapina.<\/strong> La vittima \u00e8 stata soccorsa dagli operatori del 118, ma non versa in gravi condizioni.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La vittima \u00e8 un uomo di 78 anni. Rubati 800 euro e quattro orologi.<\/p>\n","protected":false},"author":22,"featured_media":56721,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42,571],"tags":[],"class_list":["post-56720","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/56720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=56720"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/56720\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/56721"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=56720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=56720"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=56720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}