{"id":57020,"date":"2016-05-20T13:23:35","date_gmt":"2016-05-20T11:23:35","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/a-mendicino-serata-di-beneficenza-per-il-comitato-support-syrian-children\/"},"modified":"2023-01-17T12:04:31","modified_gmt":"2023-01-17T11:04:31","slug":"92220-a-mendicino-serata-di-beneficenza-per-il-comitato-support-syrian-children","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/92220-a-mendicino-serata-di-beneficenza-per-il-comitato-support-syrian-children\/","title":{"rendered":"A Mendicino serata di beneficenza per il comitato &#8216;Support Syrian Children&#8217;"},"content":{"rendered":"<p><strong>Questa sera alle\u00a020.30, al\u00a0Teatro comunale di Mendicino la\u00a0serata pro &#8220;Support Syrian Children&#8221;, ideata da Lia Lo Feudo e curata dall&#8217;Associazione culturale Milleventi.<\/strong><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>MENDICINO (CS) &#8211; L&#8217;evento solidale, presentato dalla giornalista <strong>Valentina Zinno<\/strong>, vedr\u00e0 la partecipazione della poetessa Carla Curcio, dei cantanti Krezia Cavaliere, Max Bellissario, Meron Mulugeta, Giovanna Perna e le Danzatrici di Iside.\u00a0Inoltre sar\u00e0 presentata in anteprima la mostra<strong> &#8220;Save me&#8221;<\/strong> della pittrice Patrizia Lo Feudo: un viaggio emozionale e di riflessione nelle storie che diventano vite, segnate dai volti dell&#8217;infanzia. Anche i ragazzi dell&#8217;Istituto Comprensivo di Mendicino hanno contribuito alla manifestazione grazie al supporto della prof.ssa Assunta Morrone, realizzando dei splendidi disegni sul tema della fratellanza e della pace, da omaggiare ai loro coetanei siriani.<\/p>\n<p>&nbsp;<\/p>\n<p>L&#8217;obiettivo della serata \u00e8 donare un sorriso a chi dell&#8217;infanzia ha ormai solo l&#8217;et\u00e0, perch\u00e9 la guerra e la vita terribile che ne \u00e8 conseguita in patria e fuori li ha fatti crescere troppo in fretta. Il ricavato dei biglietti e della riffa andr\u00e0 devoluto al comitato <strong>Support Syrian Children<\/strong>, con sede operativa a Bergamo, nato nell&#8217;ottobre del 2014 con lo scopo di tutelare la salute di ogni bambino che viva situazioni di difficolt\u00e0, sofferenza e disagio. In particolare \u00e8 volta alla sensibilizzazione e realizzazione di progetti a sostegno della popolazione profuga siriana, sempre con particolare riguardo a quella infantile.\u00a0Ospite d&#8217;onore della serata sar\u00e0 il Presidente del Comitato No Profit Support Syrian Children <strong>Arianna Martini<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Questa sera alle\u00a020.30, al\u00a0Teatro comunale di Mendicino la\u00a0serata pro &#8220;Support Syrian Children&#8221;, ideata da Lia Lo Feudo e curata dall&#8217;Associazione culturale Milleventi.<\/p>\n","protected":false},"author":22,"featured_media":57021,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[40,34],"tags":[],"class_list":["post-57020","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-spettacolo","category-magazine"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/57020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=57020"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/57020\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/57021"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=57020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=57020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=57020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}