{"id":57123,"date":"2016-05-23T16:11:13","date_gmt":"2016-05-23T14:11:13","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/strappa-la-catenina-doro-un-anziano-arrestata-donna-cosenza\/"},"modified":"2023-01-17T12:04:43","modified_gmt":"2023-01-17T11:04:43","slug":"92575-strappa-la-catenina-doro-un-anziano-arrestata-donna-cosenza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/92575-strappa-la-catenina-doro-un-anziano-arrestata-donna-cosenza\/","title":{"rendered":"Strappa la catenina d\u2019oro a un anziano, arrestata una donna a Cosenza"},"content":{"rendered":"<p><strong>Vittima del furto un\u2019ottantenne che passeggiava su via Santoro. Immediato il fermo\u00a0da parte dei carabinieri.<\/strong><br \/>\n<!--more--><br \/>\n&nbsp;<\/p>\n<p>COSENZA \u2013 Una donna rumena, C.E.G., di 37 anni, gi\u00e0 pregiudicata per fatti specifici, \u00e8 stata arrestata nella serata di ieri dai <strong>carabinieri per furto con strappo ai danni di un 80enne cosentino<\/strong>. Secondo quanto raccontato dall\u2019anziano, la donna ha seguito la vittima su <strong>via Santoro<\/strong> per poi strappargli dal collo una catenina d\u2019oro. Subito dopo l\u201980enne ha contattato la figlia che una volta giunta sul posto ha accompagnato il padre presso gli uffici della caserma.<br \/>\n&nbsp;<\/p>\n<p>La descrizione effettuata dall\u2019uomo ha permesso ai carabinieri di identificare e arrestare in poco tempo la donna nei pressi del centro commerciale \u201c<strong>i 2 fiumi<\/strong>\u201d. Una volta fermata, <strong>la 37enne \u00e8 stata trovata in possesso del monile che teneva celato all\u2019interno della propria maglietta ed \u00e8 stata dichiarata in stato di arresto<\/strong>, in flagranza di reato, e tradotta presso la propria abitazione in regime degli arresti domiciliari in attesa del rito direttissimo, tenutosi questa mattina, che ha portato alla convalida dell\u2019arresto e alla sua sottoposizione al regime degli arresti domiciliari in attesa del dibattimento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vittima del furto un\u2019ottantenne che passeggiava su via Santoro. Immediato il fermo\u00a0da parte dei carabinieri.<\/p>\n","protected":false},"author":22,"featured_media":57124,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42,571],"tags":[],"class_list":["post-57123","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/57123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=57123"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/57123\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/57124"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=57123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=57123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=57123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}