{"id":57492,"date":"2016-06-02T07:25:48","date_gmt":"2016-06-02T05:25:48","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/musica-a-ferramonti-concerto-del-conservatorio-di-cosenza\/"},"modified":"2023-01-17T12:05:26","modified_gmt":"2023-01-17T11:05:26","slug":"93898-musica-a-ferramonti-concerto-del-conservatorio-di-cosenza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/93898-musica-a-ferramonti-concerto-del-conservatorio-di-cosenza\/","title":{"rendered":"&#8216;Musica a Ferramonti&#8217;, concerto del Conservatorio di Cosenza"},"content":{"rendered":"<p><strong>L\u2019iniziativa del Conservatorio di Milano dal titolo \u201cSpazio della Memoria Musicale\u201d vuole essere un\u2019occasione di ricerca, catalogazione, esecuzione e fruizione delle musiche ritrovate.<\/strong> <!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Quest\u2019anno l\u2019attenzione \u00e8 rivolta al grande campo di internamento di<strong> Ferramonti<\/strong>, in Calabria. Molti deportati, tra gli oltre duemila provenienti principalmente dall\u2019Austria e dalla Germania, erano musicisti professionisti. E la musica fu uno dei pochi mezzi per tenere viva la speranza. Come a Dachau, a Buchenwald, ad Auschwitz, anche a Ferramonti si faceva musica. Suonare, in quelle circostanze, significava cercare almeno di ritrovarsi alla fine del brano di musica. Ma per tutti i deportati valeva soprattutto la speranza ultima: ritrovarsi alla fine.\u00a0Attraverso il progetto si intende non solo diffondere il valore della musica come necessit\u00e0 dello spirito umano, ma la consapevolezza della coincidenza delle realt\u00e0 musicali maturate in tutti i campi di concentramento europeo; inoltre si vuole promuovere la valorizzazione delle minoranze culturali e artistiche.<\/p>\n<p>&nbsp;<\/p>\n<p>Il programma prevede una serie di concerti (quello conclusivo a Ferramonti nel Giorno della Memoria 2017, curato dal Conservatorio \u201cG. Verdi\u201d) e momenti di approfondimento, come il Convegno- ancora a Milano- con la presentazione di un volume sulla <strong>musica nel campo di Ferramonti<\/strong> e sul compositore austriaco Kurt Sonnenfeld (1921-1997), che vi fu rinchiuso. La pubblicazione \u00e8 inserita nella collana Musica Perseguitata.\u00a0Il Conservatorio di Cosenza aderisce convintamente all\u2019iniziativa e si affianca ai partner Comune di Borgo San Dalmazzo (CN), Museo della Deportazione &#8211; Borgo San Dalmazzo (CN), Fondazione Museo Internazionale della Memoria Ferramonti di Tarsia. Comune di Tarsia, Conservatorio di Cuneo. A Cosenza, presso la Casa della Musica, domani alle\u00a020,30, studenti dei corsi superiori eseguiranno composizioni di Kurt Sonnenfeld, di Gideon Klein (che fu prigioniero nel campo di Theresienstadt) e del suo maestro Alexander von Zemlinsky.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019iniziativa del Conservatorio di Milano dal titolo \u201cSpazio della Memoria Musicale\u201d vuole essere un\u2019occasione di ricerca, catalogazione, esecuzione e fruizione delle musiche ritrovate.<\/p>\n","protected":false},"author":22,"featured_media":57493,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[40,34],"tags":[],"class_list":["post-57492","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-spettacolo","category-magazine"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/57492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=57492"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/57492\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/57493"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=57492"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=57492"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=57492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}