{"id":57619,"date":"2016-06-04T15:15:58","date_gmt":"2016-06-04T13:15:58","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/forzata-la-sede-di-ncd-a-cosenza-leone-e-bove-grave-atto-intimidatorio\/"},"modified":"2023-01-17T12:05:41","modified_gmt":"2023-01-17T11:05:41","slug":"94485-forzata-la-sede-di-ncd-a-cosenza-leone-e-bove-grave-atto-intimidatorio","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/94485-forzata-la-sede-di-ncd-a-cosenza-leone-e-bove-grave-atto-intimidatorio\/","title":{"rendered":"Forzata la sede di Ncd a Cosenza, Leone e Bove: \u201cGrave atto intimidatorio\u201d"},"content":{"rendered":"<p><strong>La denuncia degli esponenti del Comitato esecutivo regionale: \u201cClima torbido, colpiti Pino e Antonio Gentile\u201d.<\/strong><br \/>\n<!--more--><br \/>\n&nbsp;<\/p>\n<p>COSENZA \u2013 Due giorni fa la sede regionale del <strong>Nuovo centrodestra<\/strong> \u00e8 stata forzata da ignoti. Non \u00e8 stato portato via nessun documento, resta per\u00f2 il grave atto, come denunciato da Gianfranco Leone e Antonio Bove, del Comitato esecutivo regionale di Ncd. &#8220;Il grave atto intimidatorio \u2013 affermano \u2013 perpetrato ai danni della sede regionale del Nuovo Centrodestra conferma, ove ve ne fosse bisogno, l&#8217;<strong>inquinamento diffuso della competizione elettorale nella citt\u00e0 di Cosenza<\/strong>. Solo tre giorni addietro &#8211; proseguono &#8211; <strong>l&#8217;esterno della sede era stata imbrattata con frasi ingiuriose ed offensive rivolte al coordinatore regionale sen. Antonio Gentile ed al vice presidente del Consiglio regionale Pino Gentile<\/strong>. Siamo stati i primi, come lista <strong>Cosenza Popolare<\/strong> espressione del Ncd, a denunciare il clima torbido che ha contraddistinto, gi\u00e0 dalle prime fasi la campagna elettorale e le operazioni di ammissione delle liste. Questo ultimo grave atto non rester\u00e0 senza conseguenze; e si collega certamente a tutti gli episodi di intolleranza e di <strong>violenza mafiosa<\/strong> che si sono verificati negli ultimi due anni in citt\u00e0. Chiederemo ai giudici antimafia, che stanno gi\u00e0 indagando sulle irregolarit\u00e0 emerse nella gestione della cosa pubblica cosentina &#8211; concludono Leone e Bove &#8211; di fare chiarezza su mandanti ed esecutori delle gravi intimidazioni messe in atto, non solo ai danni del nostro partito, ma anche della serenit\u00e0 del voto e della libera espressione democratica della volont\u00e0 dei cittadini&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La denuncia degli esponenti del Comitato esecutivo regionale: \u201cClima torbido, colpiti Pino e Antonio Gentile\u201d.<\/p>\n","protected":false},"author":22,"featured_media":57620,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42,571],"tags":[],"class_list":["post-57619","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/57619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=57619"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/57619\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/57620"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=57619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=57619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=57619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}