{"id":57655,"date":"2016-06-06T07:07:00","date_gmt":"2016-06-06T05:07:00","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/rende-furto-nella-notte-al-bar-tabacchi-del-distributore-benzina-sulla-statale-18\/"},"modified":"2023-01-17T12:05:45","modified_gmt":"2023-01-17T11:05:45","slug":"94701-rende-furto-nella-notte-al-bar-tabacchi-del-distributore-benzina-sulla-statale-18","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/94701-rende-furto-nella-notte-al-bar-tabacchi-del-distributore-benzina-sulla-statale-18\/","title":{"rendered":"Rende, furto nella notte al bar tabacchi del distributore di benzina sulla Statale 18"},"content":{"rendered":"<p><strong>Ignoti si sono introdotti praticando un foro all&#8217;interno del bar tabacchi del distributore Ip sulla statale 18 a Rende.<\/strong><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>RENDE (CS) &#8211; Stamattina all&#8217;apertura il titolare ha scoperto il furto compiuto nella notte. Ignoti si sono introdotti all&#8217;interno del bar tabacchi &#8220;Festival Snack Bar&#8221; che fa parte del distributore di benzina Ip sulla statale 18, all&#8217;altezza del centro commerciale Campus ed hanno portato via le tre macchinette slot e i gratta e vinci presenti \u00a0all&#8217;interno. I malviventi non sono riusciti a portare via denaro perch\u00e8 non era stato lasciato l&#8217;incasso all&#8217;interno del registratore di cassa. Il titolare infatti, gi\u00e0 nei giorni scorsi aveva scoperto il tentativo di furto che purtroppo stanotte \u00e8 andato a segno. Ancora in corso di quantificazione l&#8217;ammontare del bottino da parte dei malviventi che hanno praticato un foro dalla parte posteriore dell&#8217;esercizio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ignoti si sono introdotti praticando un foro all&#8217;interno del bar tabacchi del distributore Ip sulla statale 18 a Rende.<\/p>\n","protected":false},"author":22,"featured_media":57656,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,571,44],"tags":[],"class_list":["post-57655","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-in-evidenza","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/57655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=57655"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/57655\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/57656"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=57655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=57655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=57655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}