{"id":57704,"date":"2016-06-07T07:01:36","date_gmt":"2016-06-07T05:01:36","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/scoperta-piantagione-marijuana-16-chili-sequestrati\/"},"modified":"2023-01-17T12:05:51","modified_gmt":"2023-01-17T11:05:51","slug":"94922-scoperta-piantagione-marijuana-16-chili-sequestrati","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/94922-scoperta-piantagione-marijuana-16-chili-sequestrati\/","title":{"rendered":"Scoperta una piantagione di marijuana, 16 chili sequestrati"},"content":{"rendered":"<p><strong>L&#8217;operazione \u00e8 stata compiuta dalle fiamme Gialle del Comando Provinciale della Guardia di Finanza di Reggio Calabria, Compagnia di Melito Porto Salvo<\/strong><\/p>\n<p><!--more--><\/p>\n<p>CONDOFURI (RC) &#8211; Nell\u2019ambito di una attivit\u00e0 di controllo economico-finanziario del territorio, finalizzata alla repressione del traffico e dello spaccio di sostanze stupefacenti, le fiamme gialle hanno sottoposto a sequestro, d\u2019intesa con la Procura della Repubblica di Reggio Calabria, in un terreno sito nel Comune di Condofuri Marina, una piantagione di cannabis sativa.<\/p>\n<p>Le <strong>piante<\/strong>, in ottime condizioni vegetative e ben nascoste all&#8217;interno della fitta vegetazione, erano <strong>pi\u00f9 di 200<\/strong> e avevano un&#8217;altezza media di mezzo metro. Il quantitativo sequestrato ammonta a 16 chili e 800 grammi, che sul mercato avrebbero portato un<strong> cospicuo introito alla malavita della zona<\/strong>. Oltre allo stupefacente \u00e8 stato sequestrato l\u2019intero impianto di irrigazione \u00a0\u201ca goccia\u201d per un totale di circa 300 metri. Inoltre sono stati sequestrati gli attrezzi agricoli ed i fertilizzanti utilizzati per la coltivazione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;operazione \u00e8 stata compiuta dalle fiamme Gialle del Comando Provinciale della Guardia di Finanza di Reggio Calabria, Compagnia di Melito Porto Salvo<\/p>\n","protected":false},"author":22,"featured_media":57705,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,571],"tags":[],"class_list":["post-57704","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/57704","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=57704"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/57704\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/57705"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=57704"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=57704"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=57704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}