{"id":57719,"date":"2016-06-07T13:07:36","date_gmt":"2016-06-07T11:07:36","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/plati-senza-pace-due-giorni-dal-voto-si-dimette-la-minoranza\/"},"modified":"2023-01-17T12:05:52","modified_gmt":"2023-01-17T11:05:52","slug":"95027-plati-senza-pace-due-giorni-dal-voto-si-dimette-la-minoranza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/95027-plati-senza-pace-due-giorni-dal-voto-si-dimette-la-minoranza\/","title":{"rendered":"Plat\u00ec senza pace, a due giorni dal voto si dimette la minoranza"},"content":{"rendered":"<p><strong>Colpo di scena nel comune calabrese ad alta densit\u00e0 mafiosa: \u201cIl nostro progetto non si concilia con quello dell\u2019altra lista\u201d.<\/strong><br \/>\n&nbsp;<\/p>\n<p><!--more--><\/p>\n<p>PLAT\u00cc (RC) &#8211; I consiglieri eletti con la lista uscita sconfitta alle comunali di <strong>Plat\u00ec<\/strong> che sosteneva la candidatura di <strong>Ilaria Mittiga<\/strong> hanno annunciato che si dimetteranno non appena saranno nominati. &#8220;I componenti della lista &#8216;<strong>Plat\u00ec Res Publica<\/strong>&#8216; &#8211; affermano &#8211; rendono noto che non faranno parte del Consiglio comunale di Plat\u00ec atteso che<strong> il progetto della lista non ha trovato la condivisione di 1.275 cittadini e non si concilia con il progetto della Lista &#8216;Liberi di Ricominciare'&#8221;<\/strong> che fa capo al sindaco eletto <strong>Rosario Sergi (<span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/1083\">leggi qui<\/a><\/span>)<\/strong>.<br \/>\n&nbsp;<\/p>\n<p>&#8220;<strong>Ringraziamo di cuore i 734 elettori<\/strong> che ci hanno dato la loro fiducia nella consapevolezza che condivideranno la nostra decisione&#8221; concludono i candidati-eletti della lista Plat\u00ec Res pubblica augurando &#8220;ogni bene a Plat\u00ec&#8221;. I quattro consiglieri eletti &#8211; sui 12 di cui \u00e8 composto il Consiglio &#8211; sono la candidata sindaco uscita sconfitta Ilaria Mittiga, <strong>Angela Agresta, Michele Crea e Francesco Caruso<\/strong>. La cittadina della Locride \u00e8 tornata ad avere un&#8217;amministrazione eletta dopo dieci anni di commissariamenti &#8211; intramezzati da una breve consiliatura &#8211; dovuti sia a scioglimenti per presunte infiltrazioni mafiose sia all&#8217;impossibilit\u00e0 di eleggere un sindaco per mancanza di candidati.<br \/>\n&nbsp;<\/p>\n<h2><strong>La Commissione Antimafia su Plat\u00ec<\/strong><\/h2>\n<p>La<strong> Commissione parlamentare Antimafia<\/strong> nei giorni scorsi aveva preso in esame le liste dei candidati al Consiglio Comunale del 5 giugno. &#8220;Nessun candidato \u2013 aveva detto il\u00a0vicepresidente della commissione <strong>Claudio Fava\u00a0<\/strong>riferendosi a Plat\u00ec \u2013 viola il Codice di autoregolamentazione ma decine di candidati hanno comprovati rapporti di amicizia con le cosche che gestiscono il territorio e che fanno essere concreto il pericolo che questo comune continui ad essere una democrazia sospesa&#8221;.\u00a0Sul nuovo primo cittadino <strong>Rosario Sergi<\/strong> la Commissione, nella propria relazione sugli &#8216;impresentabili&#8217;, ha rilevato che si era candidato a sindaco nel 2009 e, sconfitto, era entrato in minoranza nel Consiglio comunale poi sciolto per infiltrazioni mafiose. Sergi, inoltre, avrebbe rapporti di affinit\u00e0 con esponenti di vertice della <strong>cosca Barbaro<\/strong>. <strong>Ilaria Mittiga<\/strong>, invece, \u00e8 figlia di Francesco, sindaco all&#8217;epoca dello scioglimento per infiltrazioni mafiose del 2006.<br \/>\n&nbsp;<\/p>\n<h2><strong>Il ritiro della candidatura di Anna Rita Leonardi<\/strong><\/h2>\n<p>Lo scorso 6 maggio l\u2019esponente<strong> Anna Rita Leonardi<\/strong>, la cui candidatura a sindaco di Plat\u00ec era stata presentata alla\u00a0<strong>Leopolda<\/strong>\u00a0dal presidente del Consiglio\u00a0<strong>Matteo Renzi<\/strong>, aveva deciso di ritirarsi dalla competizione elettorale. \u201cAbbiamo dovuto constatare \u2013 aveva dichiarato \u2013 che non c\u2019erano pi\u00f9 le condizioni politiche e di agibilit\u00e0 per svolgere serenamente la campagna elettorale\u201d.<br \/>\n<strong>\u00a0<\/strong><\/p>\n<h2><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>Colpo di scena nel comune calabrese ad alta densit\u00e0 mafiosa: \u201cIl nostro progetto non si concilia con quello dell\u2019altra lista\u201d. &nbsp;<\/p>\n","protected":false},"author":22,"featured_media":57720,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,571],"tags":[],"class_list":["post-57719","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/57719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=57719"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/57719\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/57720"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=57719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=57719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=57719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}