{"id":57723,"date":"2016-06-07T14:10:46","date_gmt":"2016-06-07T12:10:46","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/elezioni-cosenza-lautocritica-del-pd-cosentini-addormentati\/"},"modified":"2023-01-17T12:05:52","modified_gmt":"2023-01-17T11:05:52","slug":"95038-elezioni-cosenza-lautocritica-del-pd-cosentini-addormentati","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/95038-elezioni-cosenza-lautocritica-del-pd-cosentini-addormentati\/","title":{"rendered":"Elezioni Cosenza, l\u2019autocritica del Pd: \u201cCosentini addormentati\u201d"},"content":{"rendered":"<p><strong>La deputata Enza Bruno Bossio non ci sta (\u201cOcchiuto? Pessima scelta\u201d), mentre Ernesto Magorno pensa\u00a0al futuro: \u201cRipartiamo da Guccione\u201d.<\/strong><!--more--><br \/>\n&nbsp;<\/p>\n<p>COSENZA \u2013 Non finisce mai di sorprendere il Partito democratico cosentino. A poche ore dalla disfatta alle elezioni comunali che hanno portato alla riconferma di <strong>Mario Occhiuto<\/strong> alla carica di sindaco, i maggiori esponenti calabresi del partito, pi\u00f9 che fare autocritica e capire le ragioni del crollo di consensi valutando eventuali passi indietro di chi sta sul ponte di comando da anni, tornano all\u2019attacco rilanciando il loro progetto di \u2018rinascita\u2019. Qualcuno preferisce anche dare la colpa ai cosentini, colpevoli di aver preferito ancora una volta Occhiuto ad una coalizione composta, tra gli altri, da personaggi come <strong>Ennio Morrone, Giacomo Mancini junior, Giuseppe Galati, Denis Verdini<\/strong> e quasi (perch\u00e9 il tentativo \u00e8\u00a0fallito) <strong>Tonino Gentile<\/strong>.<br \/>\n&nbsp;<\/p>\n<h2><strong>Enza Bruno Bossio<\/strong><\/h2>\n<p>La deputata cosentina Enza Bruno Bossio sulla sua pagina <strong>Facebook<\/strong> ieri ha manifestato tutta la sua delusione per la riconferma di Occhiuto. \u201cOggi \u00e8 un brutto giorno per Cosenza \u2013 ha scritto la parlamentare \u2013. Non si tratta di non essere sportivi o di non accettare il risultato democratico. Ma non si poteva fare una scelta peggiore per il governo della nostra citt\u00e0. <strong>Mi auguro soltanto che quando i cosentini si sveglieranno da questo incantesimo non sia ormai troppo tardi<\/strong>\u201d.<br \/>\n&nbsp;<\/p>\n<h2><strong>Ernesto Magorno<\/strong><\/h2>\n<p>Da un deputato all\u2019altro. Anche il segretario regionale del Pd Ernesto Magorno, apparso pi\u00f9 volte nervoso per i risultati elettorali di Cosenza, ha lasciato un messaggio sulla sua pagina Facebook. \u201cSin da queste ore \u2013 ha scritto \u2013 il Pd \u00e8 pienamente impegnato a sostenere il successo di Rosanna Barbieri a Crotone e di Stefano Mascaro a Rossano al voto di ballottaggio del 19 giugno. Al tempo stesso, non intendiamo rinviare, n\u00e9 sottrarci a un\u2019analisi rigorosa che richiede il voto conseguito dal Pd soprattutto nelle citt\u00e0, a partire da Cosenza. <strong>Non vogliamo limitare le ragioni che hanno determinato la sconfitta di Cosenza alla giustificazione di avere scelto il candidato sindaco in zonacesarini<\/strong>. Vogliamo prima di tutto approfondire il carattere strutturale del voto registrato da Mario Occhiuto ma anche non sorvolare sulle ragioni politiche che hanno relegato il Pd e la coalizione civica progressista ad un consenso al di sotto delle aspettative. Occhiuto \u2013 prosegue Magorno \u2013 \u00e8 riuscito a intercettare il voto proprio dello schieramento di centrodestra e di <strong>Forza Italia<\/strong>, ma al tempo stesso quello di una diffusa domanda di <strong>antipolitica<\/strong>.\u00a0Non \u00e8 un caso che, al contrario di tutte le altre citt\u00e0 meridionali al voto, il <strong>Movimento 5 stelle<\/strong> nella citt\u00e0 dei Bruzi si colloca su percentuali assai pi\u00f9 basse. <strong>Ricercare i motivi della nostra sconfitta significa indicare anche la giusta strada per aprire una nuova fase nel Partito democratico cittadino<\/strong>. <strong>Il Pd della citt\u00e0 di Cosenza richiede una rifondazione politica e organizzativa<\/strong>. Proporr\u00f2 di affidare alla responsabilit\u00e0 di <strong>Carlo Guccione<\/strong> \u2013 conclude il segretario regionale \u2013 il compito di organizzare il congresso straordinario del Partito in citt\u00e0 anche al fine di attivare rapidamente il necessario confronto con le diverse componenti sociali sul progetto di governo della \u2018Grande Cosenza\u2019 che intendiamo portare avanti anche dalla collocazione istituzionale di opposizione a Palazzo dei Bruzi\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La deputata Enza Bruno Bossio non ci sta (\u201cOcchiuto? Pessima scelta\u201d), mentre Ernesto Magorno pensa\u00a0al futuro: \u201cRipartiamo da Guccione\u201d.<\/p>\n","protected":false},"author":22,"featured_media":57724,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42,571],"tags":[],"class_list":["post-57723","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/57723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=57723"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/57723\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/57724"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=57723"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=57723"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=57723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}