{"id":57791,"date":"2016-06-09T10:22:19","date_gmt":"2016-06-09T08:22:19","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cosenza-picchia-figlio-un-martello-arrestato-quarantenne\/"},"modified":"2023-01-17T12:06:00","modified_gmt":"2023-01-17T11:06:00","slug":"95271-cosenza-picchia-figlio-un-martello-arrestato-quarantenne","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/95271-cosenza-picchia-figlio-un-martello-arrestato-quarantenne\/","title":{"rendered":"Cosenza: picchia il figlio con un martello, arrestato quarantenne"},"content":{"rendered":"<p><strong>L&#8217;uomo \u00e8 accusato di lesioni aggravate ed in passato era stato denunciato per violenza sessuale.<\/strong><\/p>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; La notte scorsa \u00e8 stato tratto in arresto Anton Georgiev Dimitrov cittadino di nazionalit\u00e0 bulgara da tempo residente a Cosenza. Il quarantenne \u00e8 ritenuto responsabile di lesioni aggravate ai danni del figlio ventiquattrenne. Ad allertare la Questura di Cosenza <strong>una telefonata in cui si segnalava un&#8217;aggressione avvenuta nei pressi di via Popilia.<\/strong> Intervenuti sul posto gli agenti hanno raccolto le testimonianze dei residenti e una volta raggiunto il Pronto Soccorso dell&#8217;Annunziata hanno individuato la vittima. Il giovane, visitato dai sanitari dell&#8217;Ospedale di Cosenza, \u00e8 stato giudicato guaribile in venti giorni dopo aver riportato un trauma cranico con ferita lacero contusa del cuoio capelluto. Incalzato dalle domande dei poliziotti il ragazzo ha confessato di essere stato colpito alla nuca con un martello dal padre.<\/p>\n<p>&nbsp;<\/p>\n<p>Il litigio sarebbe scaturito da un diverbio tra il quarantenne e la compagna nel momento in cui il giovane era intervenuto in difesa della donna. <strong>Un gesto eticamente corretto al quale l&#8217;uomo ha reagito scagliandosi con violenza contro il figlio<\/strong> e dopo averlo spintonato e afferrato per la gola ha iniziato a picchiarlo ripetutamente con un martello sul capo. Dopo aver dato sfogo alla propria ira il bulgaro \u00e8 poi scappato cercando di far perdere le proprie tracce. A rintracciarlo sono stati gli stessi agenti che lo hanno intercettato nei pressi del centro commerciale Due Fiumi e posto in stato d&#8217;arresto. L&#8217;episodio ha fatto emergere una serie di violenze e soprusi compiuti ai danni della compagna. Inoltre Gerogiev \u00e8 da ricordare come lo scorso anno fu arrestato sempre dalla squadra volante della Questura di Cosenza per violenza sessuale e porto abusivo d&#8217;armi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;uomo \u00e8 accusato di lesioni aggravate ed in passato era stato denunciato per violenza sessuale.<\/p>\n","protected":false},"author":22,"featured_media":57792,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42,571],"tags":[],"class_list":["post-57791","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/57791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=57791"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/57791\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/57792"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=57791"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=57791"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=57791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}