{"id":58086,"date":"2016-06-16T09:30:09","date_gmt":"2016-06-16T07:30:09","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/false-griffe-su-accessori-e-capi-dabbigliamento-sedici-arresti\/"},"modified":"2023-01-17T12:06:35","modified_gmt":"2023-01-17T11:06:35","slug":"96244-false-griffe-su-accessori-e-capi-dabbigliamento-sedici-arresti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/96244-false-griffe-su-accessori-e-capi-dabbigliamento-sedici-arresti\/","title":{"rendered":"&#8216;Easy Brand&#8217;, false griffe su accessori e capi d&#8217;abbigliamento. Sedici arresti (VIDEO)"},"content":{"rendered":"<p><strong>Smantellata una vera e propria &#8216;fabbrica&#8217; per taroccare i marchi d&#8217;alta moda.<\/strong><\/p>\n<p><!--more--><br \/>\nREGGIO CALABRIA &#8211; I finanzieri del Comando provinciale di Reggio Calabria hanno smantellato questa mattina un&#8217;associazione per delinquere finalizzata alla produzione e commercializzazione di capi di abbigliamento ed accessori contraffatti. Complessivamente sono state <strong>denunciate 40 persone<\/strong>, di cui <strong>16 colpite da misura cautelare personale<\/strong>.<strong> Oltre 150.000 i pezzi contraffatti sequestrati.<\/strong> Sequestrati beni per 1 milione di euro.<\/p>\n<p>Il blitz \u00e8 scattato alle prime luci dell&#8217;alba ed al termine di una articolata e complessa indagine diretta e coordinata dalla Procura della Repubblica di Reggio Calabria &#8211; Direzione Distrettuale Antimafia. Sono state eseguite 16 ordinanze di custodia cautelare, di cui 6 in carcere e 10 agli arresti domiciliari, nonch\u00e9 40 perquisizioni locali. I provvedimenti, emessi dal Gip del Tribunale di Reggio Calabria, su richiesta della Procura della Repubblica \u2013 Direzione Distrettuale Antimafia -, hanno posto fine ad una articolata organizzazione criminale, ramificata sul territorio reggino, dedita alla fabbricazione e commercializzazione di capi d\u2019abbigliamento recanti i<strong> marchi e i segni delle pi\u00f9 note griffe nazionali ed estere contraffatti.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-96302 aligncenter\" src=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2016\/06\/marchi-easy-brand.jpg\" alt=\"marchi easy brand\" width=\"461\" height=\"302\" title=\"\"><\/p>\n<p>Le<strong> accuse contestate<\/strong>, a vario titolo, sono di associazione per delinquere, contraffazione, alterazione o uso di segni distintivi di opere dell\u2019ingegno o di prodotti industriali, introduzione nello Stato e commercio di prodotti con segni falsi, frode nell\u2019esercizio del commercio e ricettazione.<\/p>\n<p>Le indagini, nate dal sequestro di migliaia di capi d\u2019abbigliamento a carico di un cittadino senegalese, nonch\u00e9 dal rinvenimento di un opificio artigianale che non poteva giustificare l\u2019enorme mole di materiale sequestrato, hanno consentito ai \u201cBaschi verdi\u201d del Gruppo di Reggio Calabria di addivenire ad una compiuta mappatura delle aree di vendita ed a delineare compiutamente l\u2019operativit\u00e0 e i ruoli dei numerosi sodali dell\u2019organizzazione. Le successive attivit\u00e0 tecniche, corroborate da appostamenti e pedinamenti, hanno portato all\u2019individuazione dell\u2019intera filiera della contraffazione, dall\u2019acquisto della materia prima \u201cvergine\u201d, direttamente in Turchia, in Cina, nonch\u00e9 in diverse regioni del territorio nazionale, al confezionamento del prodotto finale destinato a rifornire gran parte dei mercati della Provincia, nonch\u00e9 ad evadere specifici ordini commissionati anche da clienti operanti fuori dal territorio cittadino.<\/p>\n<p><strong><span style=\"color: #ff0000;\">IL VIDEO DEL BLITZ<\/span><\/strong><\/p>\n<p>[youtube url=&#8221;https:\/\/www.youtube.com\/watch?v=uz9WFxXpr1I&amp;feature=youtu.be&#8221; width=&#8221;500&#8243; height=&#8221;300&#8243;]<\/p>\n<h2><\/h2>\n<h2>Moderni macchinari per falsificare i capi<\/h2>\n<p>L\u2019Organizzazione criminale, in cui ogni sodale aveva dei ruoli ben definiti, capeggiata da Spatari Giuseppe di 54 anni e da Lo Macouna di 57 anni, inteso \u201cGiulio\u201d, cittadino italiano di origine senegalese, aveva impiantato sul territorio reggino diversi opifici attrezzati con moderni macchinari industriali per mezzo dei quali era possibile imprimere i marchi delle griffe di moda direttamente sui capi. Dagli approfondimenti investigativi \u00e8 emerso che i rei utilizzavano opifici in parte completamente clandestini ed in parte operanti in violazione delle norme sui diritti di propriet\u00e0 industriale, in quanto risultati sprovvisti di qualsiasi tipo di autorizzazione e della licenza di rivenditore ufficiale. A dimostrazione di ci\u00f2 \u00e8 stato scoperto un laboratorio tessile con regolare partita IVA ma al cui interno si perpetrava il reato.<\/p>\n<p>In tal modo il sodalizio criminale \u00e8 stato in grado di creare un vero e proprio mercato \u201cparallelo\u201d del falso di enormi dimensioni ed in grado di compromettere seriamente i canali leciti di rifornimento. Sono stati oltre 150.000 i capi di abbigliamento ed accessori contraffatti sequestrati nel corso dell\u2019indagine. Tra i danneggiati dall\u2019attivit\u00e0 illecita vi sono, chiaramente, anche i consumatori finali, i quali hanno comprato prodotti qualitativamente scadenti e, talvolta, pericolosi per la salute. L\u2019entit\u00e0 del fenomeno \u00e8 fotografata dagli esiti complessivi dell\u2019attivit\u00e0 investigativa, con la denuncia complessiva di 40 soggetti, 16 dei quali destinatari della misura cautelare personale ed il sequestro di tre immobili, sette autovetture, 18 macchinari industriali, disponibilit\u00e0 finanziarie intestate ai soggetti colpiti da misura cautelare ed oltre 150.000 capi ed accessori d\u2019abbigliamento contraffatti.<\/p>\n<h3>I soggetti colpiti dalla misura cautelare in carcere<\/h3>\n<p>1. SPATARI Giuseppe, nato a Reggio Calabria il 14\/11\/1961<br \/>\n2. CAPONE Giovanni, nato a Frattamaggiore (NA)il 07\/12\/1970<br \/>\n3. LO MACOUNA, nato in Senegal (EE) il 02\/02\/1959<br \/>\n4. GAYE El Hadji Malick, nato in Senegal (EE) il 04\/01\/1971<br \/>\n5. SINGH Jaspal, nato in India (EE) il 15\/04\/1981<br \/>\n6. SINGH Rajinder, nato in India (EE) il 04\/02\/1984<br \/>\nI soggetti colpiti dalla misura cautelare degli arresti domiciliari sono:<br \/>\n1. KRUTKO Ganna, nata in Ucraina (EE) il 07\/02\/1978<br \/>\n2. SINGH Baljit, nato in India (EE) il 20\/06\/1988<br \/>\n3. ERANO\u2019 Stefano, nato a Reggio Calabria il 07\/07\/1967<br \/>\n4. PERITI Demetrio, nato a Reggio Calabria il 15\/02\/1967<br \/>\n5. KHTIBARI Fatiha, nata in Marocco (EE) il 01\/01\/1986<br \/>\n6. KADIRI Mohammed, nato in Marocco (EE) il 29\/08\/1986<br \/>\n7. ALI HASSAN Nabil, nato in Egitto (EE) il 10\/06\/1952<br \/>\n8. FARHAT Abdelhamid, nato in Tunisia (EE) il 06\/05\/1980<br \/>\n9. SARR Mamadou Moustapha, nato in Senegal (EE) il 13\/10\/1980<br \/>\n10. SAMBA NDOYE, nato a Touba (SENEGAL) il 05\/01\/1990<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Smantellata una vera e propria &#8216;fabbrica&#8217; per taroccare i marchi d&#8217;alta moda.<\/p>\n","protected":false},"author":22,"featured_media":58087,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,571],"tags":[],"class_list":["post-58086","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/58086","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=58086"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/58086\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/58087"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=58086"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=58086"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=58086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}