{"id":58093,"date":"2016-06-16T08:00:39","date_gmt":"2016-06-16T06:00:39","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/manifestazione-no-tav-val-susa-assolta-ricercatrice-dellunical\/"},"modified":"2023-01-17T12:06:35","modified_gmt":"2023-01-17T11:06:35","slug":"96262-manifestazione-no-tav-val-susa-assolta-ricercatrice-dellunical","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/96262-manifestazione-no-tav-val-susa-assolta-ricercatrice-dellunical\/","title":{"rendered":"Manifestazione No Tav in Val di Susa, assolta ricercatrice dell&#8217;Unical"},"content":{"rendered":"<p><strong>La donna ha affermato di aver partecipato alla protesta in veste di sociologa, condannata studentessa.<\/strong><\/p>\n<p><!--more--><br \/>\nTORINO &#8211; Per avere presenziato a una delle dimostrazioni dei No Tav in Valle di Susa culminata in momenti di tensione, una studentessa di antropologia, impegnata a scrivere una tesi di laurea sul movimento, \u00e8 stata condannata oggi in tribunale a Torino a due mesi di reclusione (con la condizionale). La donna \u00e8 stata dichiarata colpevole di &#8220;concorso morale&#8221; in alcuni dei vari reati contestati dalla procura agli attivisti. La manifestazione, nell&#8217;estate del 2013 a Salbertrand (Torino), cominci\u00f2 come un volantinaggio, poi si concentr\u00f2 contr\u00f2 la sede dell&#8217;Itinera, ditta che forniva materiali per il cantiere del Tav, con il blocco di un camion ed episodi di imbrattamento. Il pm Antonio Rinaudo ha affermato che la studentessa (laureanda alla Ca&#8217; Foscari di Venezia) non si limit\u00f2 ad osservare da semplice spettatrice, tanto \u00e8 vero che nella tesi raccont\u00f2 i fatti in prima persona. <strong>Quello che per la difesa era un &#8220;espediente narrativo&#8221; era invece, per l&#8217;accusa, la prova del &#8220;contributo&#8221; alla dimostrazione.<\/strong> Per le stesse circostanze era imputata una ricercatrice di sociologia all&#8217;Universit\u00e0 di Calabria (oggi supplente in un istituto tecnico a Torino) che per\u00f2 \u00e8 stata assolta. &#8220;Il mio &#8211; ha detto uscendo dal Palagiustizia &#8211; era lo studio sul campo di un movimento sociale. Credo di non avere fatto nulla di male&#8221;. Entrambe erano difese dall&#8217;avvocato Valentina Colletta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La donna ha affermato di aver partecipato alla protesta in veste di sociologa, condannata studentessa.<\/p>\n","protected":false},"author":22,"featured_media":58094,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[571,7],"tags":[],"class_list":["post-58093","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-universita"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/58093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=58093"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/58093\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/58094"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=58093"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=58093"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=58093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}