{"id":58102,"date":"2016-06-16T09:56:25","date_gmt":"2016-06-16T07:56:25","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/flc-cgil-sullistituto-fermi-di-cosenza-la-dirigenza-ha-creato-un-clima-invivibile\/"},"modified":"2023-01-17T12:06:36","modified_gmt":"2023-01-17T11:06:36","slug":"96285-flc-cgil-sullistituto-fermi-di-cosenza-la-dirigenza-ha-creato-un-clima-invivibile","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/96285-flc-cgil-sullistituto-fermi-di-cosenza-la-dirigenza-ha-creato-un-clima-invivibile\/","title":{"rendered":"Flc Cgil sull&#8217;istituto &#8216;Fermi&#8217; di Cosenza: &#8220;la dirigenza ha creato un clima invivibile&#8221;"},"content":{"rendered":"<p><strong>Quello che \u00e8 successo ieri al \u201cFermi\u201d supera la pi\u00f9 fervida fantasia e fa emergere quella che \u00e8 la vera realt\u00e0 che si vive in quella scuola, al di l\u00e0 delle mistificanti coperture che qualcuno tenta malamente di proporre.<\/strong><\/p>\n<p><!--more--><br \/>\nCOSENZA &#8211; Dura la nota dell&#8217;organizzazione sindacale a firma di\u00a0<strong>Pino Assalone<\/strong>, segretario provinciale della FLC-CGIL e di<strong>\u00a0Ciccio Gaudio<\/strong> della Rsu Flc-Cgil.<\/p>\n<p>&#8220;Una insegnante, che sta attraversando un periodo di non positive condizioni di salute, si \u00e8 vista obbligata dalla visita fiscale a riprendere la propria attivit\u00e0 lavorativa nonostante la lavoratrice avesse esibito addirittura un certificato di uno specialista operante in struttura pubblica che attestava la malattia della lavoratrice e le terapie che segue in quella stessa struttura. Non intendiamo sostituirci a chicchessia, ma viste le condizioni di salute era proprio necessario rimandare la professoressa a svolgere il proprio lavoro? O non era invece necessaria una valutazione medica pi\u00f9 attenta? A noi sembra strana questa anomala determinazione da parte di chi in tema di salute dovrebbe deontologicamente tutelare chi vive uno stato di infermit\u00e0. Come Organizzazione Sindacale faremo di tutto perch\u00e9 emerga la verit\u00e0 su una vicenda che non pu\u00f2 essere sottaciuta e che va sicuramente approfondita&#8221;.<\/p>\n<p>&#8220;C\u2019\u00e8 di pi\u00f9 e come se non bastasse la docente comunica a scuola, l\u2019esito della visita ed il giorno successivo, come suo dovere, riprende il servizio, anche se il malessere denunciato permane forte. Ma, sorpresa, nonostante la scuola fosse pienamente a conoscenza del suo rientro, vi trova la supplente che la ha sostituita nei giorni precedenti e le viene riferito dallo staff della dirigente che non si aspettavano il suo rientro. La docente giustamente rivendica con forza il suo diritto-dovere a svolgere gli scrutini e, finalmente, si acclara questa semplicissima ovviet\u00e0&#8221;.<\/p>\n<p>&#8220;Ma la tensione accumulata dalla docente comporta che &#8211; prosegue la nota sindacale &#8211; all\u2019inizio dello scrutinio, la stessa si sente malissimo, viene chiamata un\u2019ambulanza del 118 e viene addirittura portata in pronto soccorso, dove ricever\u00e0 le attenzioni appropriate.\u00a0Mentre si vivono queste situazioni, un poco attento consiglio di istituto e propenso a discutere di pi\u00f9 su temi goliardici si \u00e8 riunito due giorni prima in seduta \u201cstraordinaria e d\u2019urgenza\u201d per \u2026 approvare la festa di fine d\u2019anno degli studenti! Un vecchio ma sempre valido panem et circenses che tende a nascondere ci\u00f2 che drammaticamente accade tristemente al \u201cFermi\u201d nella infelice era Bilotta!&#8221;.<\/p>\n<p>&#8220;Era che, per fortuna, sta per chiudersi con grande soddisfazione della gran parte dei lavoratori. L\u2019invivibilit\u00e0 del clima che si \u00e8 respirato negli ultimi cinque anni, testimoniato dalle ispezioni ministeriali che hanno ascoltato docenti ed ata arrivando a comminare l\u2019inusuale sospensione di 15 giorni alla dirigente, deve terminare insieme a questa dirigenza.\u00a0Il dirigente che verr\u00e0 avr\u00e0 il compito di riportare in questa scuola (dove non a caso si \u00e8 verificato un calo del 50% degli iscritti al primo anno ed uno del 20% del numero complessivo degli alunni) il clima di serenit\u00e0, armonia, collaborazione che appartiene al DNA di una comunit\u00e0 cooperante rivolta all\u2019istruzione ed alla formazione dei giovani come deve essere qualsiasi scuola della Repubblica italiana. Clima che questa dirigenza (e chi la ha sostenuta assumendosene pesanti responsabilit\u00e0) ha fatto perdere, attraverso una continua negazione dei diritti contrattuali, delle libert\u00e0 didattiche, della dialettica democratica ed una pratica di gestione unilaterale dell\u2019istituto che ha valorizzato non sempre le competenze e le capacit\u00e0 di quanti avevano titolo e capacit\u00e0 ad entrare a far parte di una struttura organizzativa lasciando lo spazio ad una visione piramidale della gestione della cosa pubblica. La scuola vive processi orizzontali, proprio perch\u00e9 \u00e8 comunit\u00e0 sociale, culturale che viene espressa da sintagmi organizzativi riconducibile ad una partecipazione democratica dove ognuno \u00e8 protagonista della crescita di ogni singolo istituto&#8221;.<br \/>\n&#8220;Il dirigente che verr\u00e0 dovr\u00e0 operare un\u2019inversione totale di rotta, una profonda discontinuit\u00e0 con un passato che verr\u00e0 presto confinato nel dimenticatoio insieme ai suoi protagonisti. Siamo sicuri che il personale del \u201cFermi\u201d, docenti ed ata, delegittimato e confinato a ruoli sempre pi\u00f9 marginali in questi anni, assumer\u00e0 un nuovo e vitale protagonismo di proficua partecipazione nella stagione che si aprir\u00e0. Come FLC, se la barra sar\u00e0 quella della democrazia e dei diritti, non faremo mancare la nostra fattiva collaborazione&#8221;.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quello che \u00e8 successo ieri al \u201cFermi\u201d supera la pi\u00f9 fervida fantasia e fa emergere quella che \u00e8 la vera realt\u00e0 che si vive in quella scuola, al di l\u00e0 delle mistificanti coperture che qualcuno tenta malamente di proporre.<\/p>\n","protected":false},"author":21,"featured_media":58103,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42,571],"tags":[],"class_list":["post-58102","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/58102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=58102"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/58102\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/58103"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=58102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=58102"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=58102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}