{"id":58219,"date":"2016-06-18T12:53:01","date_gmt":"2016-06-18T10:53:01","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/operaio-cade-da-impalcatura-a-castrolibero-ricoverato-in-rianimazione\/"},"modified":"2023-01-17T12:06:49","modified_gmt":"2023-01-17T11:06:49","slug":"96664-operaio-cade-da-impalcatura-a-castrolibero-ricoverato-in-rianimazione","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/96664-operaio-cade-da-impalcatura-a-castrolibero-ricoverato-in-rianimazione\/","title":{"rendered":"Operaio cade da impalcatura a Castrolibero, ricoverato in Rianimazione"},"content":{"rendered":"<p><strong>Incidente sul lavoro nell&#8217;area urbana di Cosenza, muratore in gravi condizioni.<\/strong><\/p>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>CASTROLIBERO (CS)\u00a0&#8211; Grave incidente sul lavoro oggi a Castrolibero. Intorno alle 8.00 di stamattina, S. D. operaio cosentino di 37 anni \u00e8 stato soccorso d&#8217;urgenza dopo essere caduto da un&#8217;impalcatura mentre era all&#8217;opera in uno stabile ubicato nei pressi di Serra Miceli. L&#8217;operaio si \u00e8 schiantato al suolo precipitando da un&#8217;altezza di circa sei metri ed \u00e8 stato trasportato all&#8217;ospedale dell&#8217;Annunziata di Cosenza in elisoccorso. Ricoverato nel reparto di Rianimazione, in prognosi riservata, ha riportato lesioni in varie parti del corpo. Sul fatto hanno avviato indagini i carabinieri i quali dovranno ricostruire l&#8217;esatta dinamica dei fatti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Incidente sul lavoro nell&#8217;area urbana di Cosenza, muratore in gravi condizioni.<\/p>\n","protected":false},"author":22,"featured_media":58220,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,565,571],"tags":[],"class_list":["post-58219","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-castrolibero-montalto","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/58219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=58219"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/58219\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/58220"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=58219"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=58219"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=58219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}