{"id":58265,"date":"2016-06-20T16:02:19","date_gmt":"2016-06-20T14:02:19","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/pesanti-tagli-governativi-la-provincia-di-cosenza-a-rischio-dissesto\/"},"modified":"2023-01-17T12:06:55","modified_gmt":"2023-01-17T11:06:55","slug":"96835-pesanti-tagli-governativi-la-provincia-di-cosenza-a-rischio-dissesto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/96835-pesanti-tagli-governativi-la-provincia-di-cosenza-a-rischio-dissesto\/","title":{"rendered":"Pesanti tagli governativi, la Provincia di Cosenza a rischio dissesto"},"content":{"rendered":"<p><strong>Per Cosenza\u00a0oltre 26 milioni di euro in meno.\u00a0<\/strong><\/p>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Un altro taglio di circa 26.400.000 euro, da parte del Governo per la Provincia di Cosenza, andr\u00e0 ad aggiungersi ai circa 80 milioni degli anni precedenti.\u00a0\u201cUna decisione \u2013 afferma il presidente della Provincia Mario Occhiuto &#8211; che, se dovesse essere approvata nel Decreto Enti Locali da parte del Governo nazionale, rappresenterebbe una scure che si abbatter\u00e0 su un ente locale, che <strong>continua a gestire settori importanti della vita amministrativa provinciale, come quello cruciale della viabilit\u00e0, delle scuole superiori, dell\u2019ambiente e dei trasporti.\u00a0<\/strong>Ad oggi, le entrate dell\u2019ente, come certificato dal Ministero dell\u2019economia, ammontano a circa 74 milioni di euro, contro una spesa inderogabile e difficilmente comprimibile di circa 92 milioni di euro, con un impatto in negativo, sul bilancio della Provincia, di circa 18 milioni di euro.<\/p>\n<p>&nbsp;<\/p>\n<p>Senza contare gli altri 15 milioni di euro, che occorrono per l\u2019esercizio delle funzioni fondamentali nei settori dell\u2019edilizia scolastica, delle strade e dell\u2019ambiente\u201d.\u00a0La Provincia di Cosenza gestisce, infatti, una rete viaria di circa 3000 chilometri sui quali non potr\u00e0 garantire nemmeno l\u2019ordinaria manutenzione del manto stradale, il taglio d\u2019erba e l\u2019apposizione della segnaletica, oltre a non poter intervenire neanche sulla manutenzione straordinaria, causata da smottamenti e frane, molto frequenti specie nel periodo invernale, sia nelle zone interne che sulle coste.\u00a0Uno scenario di simili disservizi potrebbe configurarsi anche per i <strong>130 edifici scolastici di competenza provinciale, per i quali, all\u2019apertura del nuovo anno scolastico, non potranno essere garantiti il riscaldamento, l\u2019energia elettrica<\/strong> e l\u2019erogazione dei fondi per il loro funzionamento.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201c<strong>Una situazione economico &#8211; \u00a0finanziaria molto difficile, per non dire drammatica \u2013 sottolinea il presidente Occhiuto<\/strong> &#8211; che non potr\u00e0 che avere serie ripercussioni sulla comunit\u00e0 provinciale. Il Bilancio per l\u2019esercizio finanziario 2016, infatti, non presenta adeguati fondi per essere approvato, a meno che il Governo non intervenga tempestivamente, rivedendo la situazione economico finanziaria delle Province, e in particolare quella di Cosenza, che per vastit\u00e0 di territorio \u00e8 tra le prime tre in Italia. Se la situazione rimanesse immutata, lo scenario che si profila \u00e8 di completa chiusura per l\u2019ente\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Per Cosenza\u00a0oltre 26 milioni di euro in meno.\u00a0<\/p>\n","protected":false},"author":22,"featured_media":58266,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[],"class_list":["post-58265","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/58265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=58265"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/58265\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/58266"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=58265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=58265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=58265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}