{"id":58532,"date":"2016-06-25T15:45:04","date_gmt":"2016-06-25T13:45:04","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/costituiti-nel-cosentino-75-comitati-si-al-referendum\/"},"modified":"2023-01-17T12:07:30","modified_gmt":"2023-01-17T11:07:30","slug":"97652-costituiti-nel-cosentino-75-comitati-si-al-referendum","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/97652-costituiti-nel-cosentino-75-comitati-si-al-referendum\/","title":{"rendered":"Costituiti nel cosentino 75 comitati per il s\u00ec al referendum"},"content":{"rendered":"<p><strong>L\u2019annuncio di Mimmo Bevacqua, che specifica: \u201cLa gran parte dei costituenti \u00e8 composta da cittadini non iscritti al Pd\u201d.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>REGGIO CALABRIA \u2013 Dopo le 11 mila forme raccolte dal segretario regionale del Pd <strong>Ernesto Magorno<\/strong>, ecco arrivare i 75 Comitati per il s\u00ec al referendum costituzionale. Ad annunciarlo \u00e8 il consigliere <strong>Mimmo Bevacqua<\/strong>, responsabile per la Calabria di <strong>Zonadem<\/strong>. &#8220;Abbiamo costituito, in provincia di Cosenza, 75 Comitati per il S\u00ec al referendum costituzionale \u2013 afferma \u2013 e raccolto circa <strong>2000 firme<\/strong>. La gran parte dei costituenti i comitati e dei sottoscrittori \u2013 tiene a specificare Bevacqua \u2013 \u00e8 composta da cittadini non iscritti al Pd, ma che vogliono concorrere a rendere chiare le ragioni che, nel merito, configurano in maniera positiva l&#8217;impianto della riforma costituzionale sulla quale saremo chiamati ad esprimerci nel prossimo autunno&#8221;.<br \/>\n&nbsp;<\/p>\n<p>&#8220;Si tratta &#8211; sostiene Bevacqua &#8211; di un&#8217;<strong>apertura alla societ\u00e0 civile che vuole andare oltre quegli angusti steccati dell&#8217;appartenenza di partito<\/strong> e quelle discussioni interne riservate sinora alla ristretta cerchia degli addetti ai lavori che hanno dimostrato di essere sempre pi\u00f9 autoreferenziali e lontane dai territori. Proprio l&#8217;impegno per la riforma costituzionale pu\u00f2 rappresentare un&#8217;occasione per la ricezione di istanze e l&#8217;elaborazione di proposte che possono far recuperare al Pd le ragioni essenziali della sua nascita e della sua esistenza&#8221;.<br \/>\n&nbsp;<\/p>\n<p>&#8220;Siamo fermamente convinti &#8211; sottolinea ancora Bevacqua &#8211; che, dopo decenni di sforzi vani e privi di risultati, il parlamento abbia licenziato un testo che affronta efficacemente alcune fra le maggiori emergenze istituzionali del nostro Paese, a cominciare dal superamento dell&#8217;anacronistico bicameralismo paritario indifferenziato e dal disegno di un regionalismo collaborativo pi\u00f9 maturo e non inficiato dai continui ricorsi ai conflitti di attribuzione fra i diversi livelli istituzionali. Ringraziando i molti giovani e donne, professionisti e provenienti dal mondo del lavoro, che cos\u00ec numerosi hanno voluto manifestare la loro partecipazione, fra i comitati presenti nei Comuni maggiori della provincia ricordo quelli di <strong>Cosenza, Rende, Corigliano, Rossano, Acri, Montalto, Trebisacce, Castrolibero, Amantea, Cetraro, Fuscaldo, San Nicola Arcella, Mendicino, Mirto Crosia, Cariati, Roggiano Gravina, Oriolo, Cetraro, San Sosti, Celico, Rovito, Cerchiara, Aprigliano, Longobucco<\/strong>&#8220;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019annuncio di Mimmo Bevacqua, che specifica: \u201cLa gran parte dei costituenti \u00e8 composta da cittadini non iscritti al Pd\u201d. &nbsp; REGGIO CALABRIA \u2013 Dopo le 11 mila forme raccolte dal segretario regionale del Pd Ernesto Magorno, ecco arrivare i 75 Comitati per il s\u00ec al referendum costituzionale. Ad annunciarlo \u00e8 il consigliere Mimmo Bevacqua, responsabile [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":58533,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[571,28],"tags":[],"class_list":["post-58532","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/58532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=58532"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/58532\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/58533"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=58532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=58532"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=58532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}