{"id":58671,"date":"2016-06-30T04:00:00","date_gmt":"2016-06-30T02:00:00","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/referendum-costituzionale-cosenza-arriva-ferdinando-imposimato\/"},"modified":"2023-01-17T12:07:49","modified_gmt":"2023-01-17T11:07:49","slug":"98137-referendum-costituzionale-cosenza-arriva-ferdinando-imposimato","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/98137-referendum-costituzionale-cosenza-arriva-ferdinando-imposimato\/","title":{"rendered":"Referendum Costituzionale, a Cosenza arriva Ferdinando Imposimato"},"content":{"rendered":"<p><strong>Iniziativa del Movimento 5 Stelle luned\u00ec 4 luglio. Presenti il presidente Onorario Aggiunto alla Suprema Corte di Cassazione, Nicola Morra e Silvio Gambino.<\/strong><!--more--><br \/>\n&nbsp;<\/p>\n<p>COSENZA \u2013 Si torna a parlare di <strong>Referendum Costituzionale<\/strong> a Cosenza. Il MoVimento 5 Stelle, infatti, ha organizzato per luned\u00ec prossimo <strong>4 luglio alle ore 18.30, in piazza Kennedy<\/strong>, un incontro dibattito dal significativo titolo &#8216;<strong>Le ragioni del NO&#8217;<\/strong>.\u00a0All\u2019evento parteciperanno: <strong>Ferdinando Imposimato<\/strong> (presidente onorario Aggiunto alla Suprema Corte di Cassazione), <strong>Silvio Gambino<\/strong>, (professore Ordinario di diritto pubblico Unical e Presidente Comitato per il NO), <strong>Nicola Morra<\/strong>, (portavoce al Senato del M5S).<br \/>\n&nbsp;<\/p>\n<p>\u201cSaranno esposte le ragioni del NO \u2013 riporta una nota \u2013 ad una riforma costituzionale voluta da Renzi-Boschi che \u2018deforma\u2019 la Costituzione e cambier\u00e0 il volto della nostra Repubblica. Partecipare per comprendere meglio \u00e8 necessario perch\u00e9 si sta prospettando il pericolo di una sottrazione della sovranit\u00e0 popolare. E\u2019 compito di ognuno difendere la Costituzione da modifiche che mirano a limitare l\u2019esercizio della democrazia.<br \/>\n&nbsp;<\/p>\n<h2><strong>Morra<\/strong><\/h2>\n<p>Per il senatore Nicola Morra \u201c<strong>c\u2019\u00e8 bisogno di rafforzare la sovranit\u00e0 dei cittadini<\/strong>, non di ridurre gli spazi di democrazia e di partecipazione ed evitare i rischi di un sistema istituzionale che vede meno contrappesi e un <strong>rafforzamento abnorme del ruolo e dei poteri del governo e del presidente del consiglio<\/strong>, in particolare, quale emerge dal <strong>ddl Boschi<\/strong>\u201d.<\/p>\n<p>\u201cIl M5S \u2013 continua la nota \u2013 ritiene che, in vista di un appuntamento referendario di cos\u00ec grande rilevanza, sia di grande importanza per i cittadini la conoscenza delle tematiche sulle quali saranno in autunno chiamati ad esprimersi e la discussione nel merito delle modifiche costituzionali approvate dal Parlamento. L\u2019incontro rappresenta uno dei primi momenti di dibattito e confronto sul territorio provinciale, dopo la <strong>raccolta di firme realizzata dal Comitato per il NO<\/strong>, a cui seguiranno diversi altri che verranno organizzati per consentire a tutti di conoscere, approfondire e dibattere questioni di grande rilevanza, anzi decisive, per il futuro del nostro Paese e per l\u2019assetto democratico delle nostre Istituzioni. Il M5S invita, quindi, tutta la cittadinanza a partecipare\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Iniziativa del Movimento 5 Stelle luned\u00ec 4 luglio. Presenti il presidente Onorario Aggiunto alla Suprema Corte di Cassazione, Nicola Morra e Silvio Gambino.<\/p>\n","protected":false},"author":22,"featured_media":58672,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42,571],"tags":[],"class_list":["post-58671","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/58671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=58671"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/58671\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/58672"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=58671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=58671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=58671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}