{"id":58760,"date":"2016-07-01T13:12:17","date_gmt":"2016-07-01T11:12:17","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/interrogazione-parlamentare-sul-liceo-fermi-cosenza\/"},"modified":"2023-01-17T12:08:00","modified_gmt":"2023-01-17T11:08:00","slug":"98460-interrogazione-parlamentare-sul-liceo-fermi-cosenza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/98460-interrogazione-parlamentare-sul-liceo-fermi-cosenza\/","title":{"rendered":"Interrogazione parlamentare sul Liceo \u2018Fermi\u2019 di Cosenza"},"content":{"rendered":"<p><strong>La denuncia del senatore Francesco Molinari e di altri 10 parlamentari: \u201cScarsa trasparenza, abuso di potere e grave vulnus democratico\u201d.<\/strong><!--more--><br \/>\n&nbsp;<\/p>\n<p>COSENZA \u2013 Il senatore Francesco Molinari insieme ai parlamentari Vacciano, Bignami, Simeoni, Bocchino, Barozzino, Romani, Campanella, Fucksia, hanno firmato un\u2019interrogazione al ministero dell\u2019Istruzione sul \u2018caso\u2019 del Liceo scientifico \u2018Fermi\u2019 di Cosenza. \u201cIn seguito alla nomina di dirigente scolastico della professoressa Michela Bilotta al Liceo \u2018E. Fermi\u2019 \u2013 dichiara Molinari \u2013 una delle realt\u00e0 formative pi\u00f9 note di Cosenza e della Calabria, fu segnalato, a suo tempo, dalla <strong>Flc-Cgil<\/strong> calabrese l&#8217;inadeguatezza degli affidamenti degli incarichi ai dirigenti scolastici nella <strong>Regione Calabria<\/strong>, ad opera del Direttore generale dell&#8217;Ufficio scolastico regionale, per scarsa trasparenza ed oggettivit\u00e0, soprattutto in scuole di grandi dimensioni. Occorre dire che, dal settembre del 2011 ad oggi, tale constatazione ha assunto connotazioni drammatiche, per quello che fu il prestigioso liceo scientifico, che ho avuto anche l&#8217;onore di frequentare e di essere rappresentante degli studenti nel Consiglio d&#8217;Istituto per due anni consecutivi, ai tempi del compianto <strong>Preside De Franco<\/strong>, grande latinista e studioso eccelso del pensiero di <strong>Telesio<\/strong>\u201d.<br \/>\n&nbsp;<\/p>\n<p>\u201cEra un obbligo per me \u2013 continua Molinari \u2013 dunque, intervenire con un atto nei confronti di un Ministero che ha fatto orecchie da mercante, pur essendo sempre stato a conoscenza di tutti i discutibili episodi in cui si \u00e8 trovata coinvolta la Preside in questione e che, tra l&#8217;altro, hanno costituito oggetto di numerose interrogazioni parlamentari, oltre che in seno al <strong>Consiglio regionale calabrese<\/strong>. Purtroppo inutilmente. Conseguenza di ci\u00f2 \u00e8 stata<strong> la pericolosissima deriva del Liceo, che ha accusato un calo del 50% degli iscritti al primo anno ed uno del 20% del numero complessivo degli alunni<\/strong>. Un grave danno, dunque, per l&#8217;istruzione e la formazione dei giovani in terra di Calabria. In merito al discutibile comportamento della Preside, peraltro di pubblico dominio ed emerso in non pochi episodi, vorrei ricordare, la vergognosa proposta di introdurre nell&#8217;anno scolastico 2013\/2014 corsi di recupero privati a pagamento per gli studenti con debito formativo, introducendo nelle scuole pubbliche un&#8217;inedita quanto sconosciuta attivit\u00e0 intra moenia, per la quale aveva addirittura provveduto a stabilire un accordo con un istituto di credito per il finanziamento \u2018a condizioni agevolatissime\u2019 dei corsi di sostegno\/studio. Anche solo questo \u2013 afferma ancora Molinari \u2013 sarebbe potuto bastare, a far venir meno una cos\u00ec poco prestigiosa guida di una cos\u00ec prestigiosa scuola e, invece, si \u00e8 optato per la riconferma, nel luglio 2014, da parte di chi, pochi mesi dopo, ha sottoposto il \u2018Fermi\u2019 ad un&#8217;ispezione durata mesi, dei quali non si conoscono gli esiti, se non parzialmente. E sono storia recente le ulteriori gravi notizie, emerse da fonti sindacali, di un docente obbligato da visita fiscale a riprendere la propria attivit\u00e0 lavorativa, nonostante esibizione di certificato di uno specialista operante in struttura pubblica attestante le precarie condizioni di salute del lavoratore. Tutto ci\u00f2 senza che si fosse messo il docente nelle condizioni di riprendere il posto di lavoro (con il supplente ancora nelle funzioni assegnate dal Dirigente scolastico), durante il delicato momento dello svolgimento degli scrutinii. Le tensioni scaricatesi in tale frangente hanno provocato un malore del docente richiamato, costretto a richiedere l&#8217;intervento del 118, con ricovero in emergenza. O come la recente festa di fine anno scolastico. In quella occasione per la partecipazione \u00e8 stato richiesto un &#8220;biglietto d&#8217;ingresso&#8221; di 10 euro da devolvere agli \u2018organizzatori\u2019, non \u00e8 dato sapere per coprire quali costi, e di cui, a tutt&#8217;oggi, non \u00e8 stato reso pubblico il contenuto del verbale di seduta con cui sono stati concessi gli spazi scolastici, n\u00e9 le modalit\u00e0 con cui \u00e8 stata ripristinata l&#8217;igiene dei luoghi e il reperimento dei fondi necessari a ci\u00f2. Eppure, la <strong>Preside forte, probabilmente, di chiss\u00e0 quale \u2018ala protrettrice\u2019, ha presentato ricorso al Giudice del lavoro contro il suo recente pensionamento<\/strong>, su decreto del Direttore generale dell&#8217;Ufficio scolastico regionale per la Calabria, con l&#8217;inquietante particolare che a decidere del medesimo sar\u00e0 un magistrato la cui figlia pare frequenti proprio il Liceo \u2018Fermi\u2019 di Cosenza. Attendiamo conferme o smentite dal Ministero \u2013 conclude Molinari \u2013 sperando che si possa fare luce e restituire dignit\u00e0 ad un istituto scolastico dalla storia prestigiosa\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La denuncia del senatore Francesco Molinari e di altri 10 parlamentari: \u201cScarsa trasparenza, abuso di potere e grave vulnus democratico\u201d.<\/p>\n","protected":false},"author":22,"featured_media":58761,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42,571],"tags":[],"class_list":["post-58760","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/58760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=58760"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/58760\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/58761"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=58760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=58760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=58760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}