{"id":58886,"date":"2016-07-05T13:15:33","date_gmt":"2016-07-05T11:15:33","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/la-goletta-verde-legambiente-arriva-domani-calabria\/"},"modified":"2023-01-17T12:08:17","modified_gmt":"2023-01-17T11:08:17","slug":"98902-la-goletta-verde-legambiente-arriva-domani-calabria","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/98902-la-goletta-verde-legambiente-arriva-domani-calabria\/","title":{"rendered":"La Goletta Verde di Legambiente arriva in Calabria per difendere le coste (AUDIO)"},"content":{"rendered":"<p><strong>Anche quest&#8217;estate la\u00a0storica imbarcazione di Legambiente\u00a0\u00e8 partita per difendere i mari e le coste italiane.<\/strong> <!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>CETRARO (CS) &#8211; Un servizio che, da ben 30 anni, \u00e8 fedele alla sua missione di analisi della qualit\u00e0 delle acque, di denuncia dell\u2019inquinamento e della scarsa e inefficiente depurazione dei reflui, delle speculazioni edilizie e della cattiva gestione delle coste italiane. Una missione che con caparbiet\u00e0\u00a0si dedica a proteggere il mare e le coste dalle illegalit\u00e0 di ogni sorta e a valorizzare, invece, il patrimonio unico del nostro Paese.\u00a0Un viaggio lungo le coste della Penisola &#8211; realizzato grazie al sostegno del Consorzio obbligatorio degli oli usati (COOU) e dei partner tecnici NAU e Novamont &#8211; che terminer\u00e0 a Ferragosto in Friuli-Venezia Giulia. L\u2019imbarcazione ambientalista arriver\u00e0 <strong>domani a Cetraro<\/strong>: primo appuntamento alle 10.30 al Lido Capannina per la seconda edizione di <strong>Ricicla Estate Calabria<\/strong>, la campagna di sensibilizzazione promossa da Legambiente Calabria e Conai, con il contributo di Alessco, per promuovere la raccolta differenziata anche in vacanza.<\/p>\n<p>Un&#8217;iniziativa molto importante che mira soprattutto a sensibilizzare sulla salvaguardia del mare e delle coste come ha sottolineato il presidente di Legambiente Calabria, <strong>Francesco Falcone<\/strong>, ai microfoni di <strong>Rlb Radioattiva<\/strong><\/p>\n<p><span style=\"color: #ff0000;\"><strong>ASCOLTA L&#8217;INTERVISTA<\/strong><\/span><\/p>\n<p>[audio_mp3 url=&#8221;http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2016\/07\/Francesco-Falcone-Legambiente.mp3&#8243;]<\/p>\n<p>Sar\u00e0 invece possibile visitare la Goletta Verde, ormeggiata al porto di Cetraro, dalle 17.30 alle 19.00. Alle 16,00 a Tortora (al Lido 2000 in via F.lli Bandiera), invece, ci sar\u00e0 l\u2019incontro su <strong>\u201cBonifiche, le eterne incompiute: Marlane e fiume Noce\u201d<\/strong>. Intervengono: Francesco Falcone, presidente Legambiente Calabria; Giovanni Moccia, presidente del comitato per le bonifiche dei terreni, fiumi e mari della Calabria; Pasquale Lamboglia, sindaco di Tortora; Giorgio Zampetti,responsabile scientifico Legambiente.\u00a0Dal 1986, anno in cui \u00e8 partita la campagna, <strong>Goletta Verde<\/strong> non ha mai smesso di opporsi a chi saccheggia il mare, rinnovando estate dopo estate le sue battaglie a seconda delle vertenze pi\u00f9 impellenti, come quella contro le fonti fossili che accompagner\u00e0 anche quest\u2019anno l\u2019imbarcazione in ogni porto o quella contro gli scarichi illegali e la mancata depurazione.<\/p>\n<p>&nbsp;<\/p>\n<p>E i dati del dossier <strong>Mare Monstrum<\/strong> di Legambiente dimostrano quanto sia critica la situazione del \u201cmare illegale\u201d anche in questa regione. I reati ai danni del mare che le forze dell\u2019ordine e le Capitanerie di porto hanno intercettato in Calabria nel corso del 2015 sono stati 1838 (il 10% a livello nazionale) con 1830 persone arrestate e denunciate e 607 sequestri. Numeri che piazzano la\u00a0Calabria al quarto posto in Italia nella classifica del mare illegale, dietro Campania, Sicilia e Lazio.\u00a0A fare la parte del leone, cos\u00ec come in buona parte dell\u2019Italia, \u00e8 il settore della pesca di frodo dove le forze dell\u2019ordine hanno scoperto 637 infrazioni. Molto alti, e in crescita, i <strong>reati legati al ciclo del cemento<\/strong>, dove la Calabria \u00e8 al secondo posto in Italia con 593 infrazioni accertate, 560 persone denunciate e 186 sequestri; seguito dalle infrazioni relative alla cattiva depurazione e agli scarichi selvaggi e da quelle relative alla pesca di frodo. Infine, da non sottovalutare, la navigazione fuorilegge.<\/p>\n<p>&nbsp;<\/p>\n<p>Con <strong>SOS Goletta<\/strong>, come sempre Legambiente assegna un compito importante a cittadini e turisti, a cui chiede di segnalare situazioni anomale foriere di inquinamento delle acque: tubi che scaricano direttamente in mare ma anche chiazze sospette. Ancora oggi, infatti, in Italia il 25% delle acque di fogna viene scaricato in mare, nei laghi e nei fiumi senza essere opportunamente depurato. Per questo, il team di tecnici che accompagna la Goletta per condurre il monitoraggio scientifico delle acque, a caccia dei punti pi\u00f9 critici, raccoglie anche le segnalazioni dei cittadini per approfondire la denuncia e farla arrivare alle autorit\u00e0 competenti. Per segnalare il \u201cmare sporco\u201d ci si pu\u00f2 collegare <span style=\"color: #0000ff;\">a<a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/1164\" target=\"_blank\" data-saferedirecturl=\"https:\/\/www.google.com\/url?hl=it&amp;q=http:\/\/www.legambiente.it\/golettaverde&amp;source=gmail&amp;ust=1467809258481000&amp;usg=AFQjCNHTj9QNc24P--7ZeyaFoV3KfXP1rw\" rel=\"noopener\">www.legambiente.it\/<wbr \/>golettaverde<\/a><\/span> o scrivere a <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"mailto:sosgoletta@legambiente.it\" target=\"_blank\" rel=\"noopener\">sosgoletta@legambiente.it<\/a><\/span> inviando una breve descrizione della situazione, l\u2019indirizzo e le indicazioni utili per identificare il punto, le foto dello scarico o dell\u2019area inquinata e un recapito telefonico.<\/p>\n<p>&nbsp;<\/p>\n<p>I\u00a0comportamenti virtuosi e i provvedimenti importanti degli ultimi 30 anni nel nostro Paese, sono raccontati in\u00a0una <strong>mostra itinerante <\/strong>realizzata con il patrocinio del ministero dell\u2019Ambiente e della Tutela del Territorio e del mare e la collaborazione di Ferderparchi, del parco nazionale dell\u2019Arcipelago Toscano e delle aree marine protette di Cinque Terre, Secche di Tor Paterno, Regno di Nettuno, Costa degli Infreschi e della Masseta, Capo Carbonara, Isole Egadi e Isola di Ustica. Dal monitoraggio della qualit\u00e0 delle acque, alla legge sulle aree protette e sulla conservazione degli ecosistemi e della biodiversit\u00e0, passando per la prima commissione parlamentare d\u2019inchiesta sul ciclo dei rifiuti, le battaglie contro i condoni edilizi e gli abbattimenti degli abusi, e infine la legge tanto attesa sugli ecoreati.<\/p>\n<p>&nbsp;<\/p>\n<p>Per la prima volta, infine, durante il viaggio di Goletta Verde, saranno organizzati, inoltre, da Altrafoto e Legambiente, workshop dedicati al reportage ambientale. <strong>Diventa EcoReporter <\/strong>\u00e8 il nome di cinque appuntamenti di quattro giorni (Sicilia 7-10 luglio, Calabria 14-17 luglio, Puglia 21-24 luglio, Marche e Emilia Romagna 29-31 luglio, Veneto e Friuli Venezia Giulia 4-7 agosto) al seguito dei tecnici di Goletta Verde, per un reportage fotografico del loro lavoro, sotto la supervisione del fotografo Piero Leonardi in qualit\u00e0 di docente. Previste anche escursioni alla ricerca di siti inquinati. Tutte le informazioni sono disponibili sul sito di Altrafoto<a href=\"https:\/\/quicosenza.it\/news\/1165\">\u00a0<span style=\"color: #0000ff;\">http:\/\/www.altrafoto.com\/corsi\/index.php?option=com_content&amp;view=article&amp;id=21&amp;Itemid=21<\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anche quest&#8217;estate la\u00a0storica imbarcazione di Legambiente\u00a0\u00e8 partita per difendere i mari e le coste italiane.<\/p>\n","protected":false},"author":22,"featured_media":58887,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[34,13],"tags":[],"class_list":["post-58886","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-magazine","category-qui-green"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/58886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=58886"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/58886\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/58887"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=58886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=58886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=58886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}