{"id":58951,"date":"2016-07-07T06:23:18","date_gmt":"2016-07-07T04:23:18","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/truffa-malversazione-onlus-nel-mirino-della-finanza\/"},"modified":"2023-01-17T12:08:24","modified_gmt":"2023-01-17T11:08:24","slug":"99131-truffa-malversazione-onlus-nel-mirino-della-finanza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/99131-truffa-malversazione-onlus-nel-mirino-della-finanza\/","title":{"rendered":"Fondi pubblici per corsi di formazione inesistenti, Onlus finisce nel mirino della Finanza"},"content":{"rendered":"<p><strong>Due denunce sono scattate al termine di un\u2019attivit\u00e0 investigativa condotta dal Nucleo Polizia Tributaria di Crotone, che ha scoperto presunte irregolarit\u00e0 nella gestione di corsi di formazione professionale per operatori socio-sanitari finanziati dalla Regione Calabria nel 2012.<\/strong><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>CROTONE &#8211; I due rappresentanti legali di un\u2019organizzazione non lucrativa di utilit\u00e0 sociale, operante nella provincia di Crotone, sono stati denunciati alla Procura della Repubblica con l&#8217;accusa di truffa aggravata per il conseguimento di <strong>erogazioni pubbliche<\/strong>, falsit\u00e0 ideologica e malversazione ai danni dello Stato.<\/p>\n<p>La <strong>Onlus<\/strong> in questione aveva ottenuto dalla Regione un anticipo di finanziamento per<strong> 315.000 euro<\/strong> a fronte delle spese sostenute per l\u2019organizzazione dei corsi. Grazie ai capillari accertamenti eseguiti dai finanzieri, anche mediante l\u2019acquisizione di documentazione bancaria, \u00e8 emerso che in realt\u00e0 tali spese erano rappresentate per ben <strong>210.000 euro<\/strong> da costi inesistenti o inammissibili ai fini del finanziamento, avendo l\u2019organizzazione addirittura dichiarato di <strong>aver retribuito i tutor<\/strong> impegnati nella formazione degli allievi , che, invece, ad oggi, non risultano aver percepito alcuna retribuzione, mentre la restante quota di 105.000 euro \u00e8 risulta essere stata distratta direttamente in favore degli indagati o di societ\u00e0 commerciali ad essi riconducibili.<\/p>\n<p>Gli <strong>indagati<\/strong> sono stati, inoltre, <strong>segnalati<\/strong> alla Procura Regionale delle Corte dei Conti per <strong>danno erariale<\/strong> in relazione alle somme indebitamente percepite o distratte. Infine, in esecuzione di apposito provvedimento cautelare emesso dal Giudice per le Indagini Preliminari presso il Tribunale di Crotone, i finanzieri crotonesi hanno sottoposto a sequestro preventivo somme di danaro e beni immobili nella disponibilit\u00e0 degli indagati fino a concorrenza dell\u2019importo di 315.000 euro, quale profitto indebitamente conseguito.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Due denunce sono scattate al termine di un\u2019attivit\u00e0 investigativa condotta dal Nucleo Polizia Tributaria di Crotone, che ha scoperto presunte irregolarit\u00e0 nella gestione di corsi di formazione professionale per operatori socio-sanitari finanziati dalla Regione Calabria nel 2012.<\/p>\n","protected":false},"author":22,"featured_media":58952,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,571],"tags":[],"class_list":["post-58951","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/58951","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=58951"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/58951\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/58952"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=58951"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=58951"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=58951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}