{"id":58961,"date":"2016-07-07T09:02:52","date_gmt":"2016-07-07T07:02:52","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/lungofiume-boulevard-domenica-tiromancino-concerto\/"},"modified":"2023-01-17T12:08:25","modified_gmt":"2023-01-17T11:08:25","slug":"99148-lungofiume-boulevard-domenica-tiromancino-concerto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/99148-lungofiume-boulevard-domenica-tiromancino-concerto\/","title":{"rendered":"Lungofiume Boulevard, domenica Tiromancino in concerto (AUDIO)"},"content":{"rendered":"<p><strong>Primi big sul palco del Lungofiume di Cosenza. Domenica 10 luglio, di scena i Tiromancino, la band romana capitanata da Federico Zampaglione.<\/strong><!--more--><\/p>\n<p>COSENZA &#8211; Una musicalit\u00e0 non convenzionale, sonorit\u00e0 che dall&#8217;inizio della loro carriera, nel 1989, si sono contraddistinte per una forma ed una vocalit\u00e0 unica e calda. I Tiromancino tornati col nuovo album intitolato &#8220;Nel respiro del mondo&#8221;, saliranno domenica sera sul palco centrale del Lungofiume Boulevard di Cosenza.<\/p>\n<p>Il suono delle chitarre acustiche, dei campionatori e degli strumenti elettronici caratterizzano i primi anni di &#8216;gloria&#8217; dei <strong>Tiromancino<\/strong> che raggiungono un apice di successo con brani quali Due Destini, La descrizione di un attimo, Amore Impossibile e ancora Strade, canzone con la quale hanno partecipato nel 2000 al Festival di Sanremo. Il brano &#8216;Due Destini&#8217; invece, ottiene un successo straordinario anche perch\u00e8 inserito nella colonna sonora del film di Ferzan \u00d6zpetek <strong>&#8220;Le fate ignoranti&#8221;<\/strong>.<\/p>\n<p>Dalla Calabria hanno ricevuto, nel settembre 2008, il &#8220;<strong>Riccio d&#8217;Argento<\/strong>&#8221; per i &#8220;migliori testi dell&#8217;anno&#8221;, oscar del live d&#8217;autore della rassegna Fatti di Musica ideata e diretta da Ruggero Pegna. L&#8217;album che da il nome al tour \u00e8 uscito lo scorso 4 marzo, lanciato con il singolo intitolato &#8216;<strong>Piccoli miracoli&#8217;<\/strong>. Si tratta dell&#8217;undicesimo album dei Tiromancino &#8220;<strong>Nel respiro del mondo<\/strong>&#8220;. Un disco contemporaneo, contaminato, ricco di sperimentazione, di sonorit\u00e0 etniche ed elettroniche. Un disco che conferma<strong> l&#8217;identit\u00e0 dei Tiromancino<\/strong> ma meno pop e con tante novit\u00e0. Tra i brani pi\u00f9 radiofonici c\u2019\u00e8 Imprevedibile, ma sono da ascoltare anche &#8220;L\u2019ultimo treno della notte&#8221;, &#8220;Mare aperto&#8221;&#8230; e la romantica &#8220;Onda che vai&#8221;.<\/p>\n<p>L&#8217;amministrazione comunale di Cosenza, ed in particolare l&#8217;assessorato diretto da <strong>Rosaria Succurro<\/strong>, ha impiegato una settimana soltanto a chiudere il live, che sicuramente sar\u00e0 molto partecipato come la stessa Succurro ha sottolineato ai microfoni di <strong>Rlb Radioattiva<\/strong><\/p>\n<p><span style=\"color: #ff0000;\"><strong>ASCOLTA L&#8217;INTERVISTA<\/strong><\/span><\/p>\n<p>[audio_mp3 url=&#8221;http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2016\/07\/Succurro-su-Tiromancino.mp3&#8243;]<\/p>\n<p>Da oggi dunque, parte ufficialmente una nuova programmazione al Lungofiume Boulevard, caratterizzata ancora da tante isole di gusto, momenti di musica live nei palchetti dislocati nell&#8217;area alle pendici del centro storico e tantissime <strong>iniziative per i pi\u00f9 piccoli, ogni giorno, dalle 18 alle 20, fino al 7 agosto.<\/strong><\/p>\n<p><strong>Il singolo &#8216;Piccoli Miracoli&#8217; che ha lanciato l&#8217;album dei Tiromancino<\/strong><\/p>\n<p>[youtube url=&#8221;https:\/\/www.youtube.com\/watch?v=NiA4Ur0Th-0&amp;list=PLPrFJ0IECkT1REWMCQg-oq4TLZFqT1ihY&amp;index=1&#8243; width=&#8221;500&#8243; height=&#8221;300&#8243;]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Primi big sul palco del Lungofiume di Cosenza. Domenica 10 luglio, di scena i Tiromancino, la band romana capitanata da Federico Zampaglione.<\/p>\n","protected":false},"author":22,"featured_media":58962,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[40,571,34],"tags":[],"class_list":["post-58961","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-spettacolo","category-in-evidenza","category-magazine"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/58961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=58961"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/58961\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/58962"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=58961"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=58961"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=58961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}