{"id":59055,"date":"2016-07-08T15:47:52","date_gmt":"2016-07-08T13:47:52","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/ragazzo-muore-corigliano-bagno\/"},"modified":"2023-01-17T12:08:37","modified_gmt":"2023-01-17T11:08:37","slug":"99381-ragazzo-muore-corigliano-bagno","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/99381-ragazzo-muore-corigliano-bagno\/","title":{"rendered":"Ragazzo muore a Corigliano mentre fa il bagno"},"content":{"rendered":"<p><strong>Era giunto in Calabria dall\u2019Africa pochi giorni fa. L\u2019annegamento probabilmente a causa di una congestione.<\/strong><!--more--><br \/>\n&nbsp;<\/p>\n<p>CORIGLIANO CALABRO (CS) \u2013 Strano scherzo destino per un giovane migrante. Era giunto dall\u2019<strong>Africa<\/strong> in Italia, precisamente a <strong>Corigliano Calabro<\/strong>, pochi giorni fa e risiedeva insieme ad altri giovani nel Palazzetto dello Sport adibito a centro di accoglienza. Oggi il <strong>minore<\/strong> \u00e8 annegato mentre faceva il bagno nel mare di <strong>Schiavonea<\/strong>. Gli amici che erano con lui hanno tentato di soccorrerlo nel momento in cui hanno visto che era in difficolt\u00e0 ma era ormai troppo tardi. Il ragazzo era gi\u00e0 morto annegato, probabilmente per una congestione. Sul posto sono intervenuti i carabinieri ed il personale del 118 che ha confermato il decesso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Era giunto in Calabria dall\u2019Africa pochi giorni fa. L\u2019annegamento probabilmente a causa di una congestione.<\/p>\n","protected":false},"author":22,"featured_media":59056,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[571,28],"tags":[],"class_list":["post-59055","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/59055","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=59055"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/59055\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/59056"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=59055"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=59055"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=59055"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}