{"id":5911,"date":"2012-10-17T10:28:19","date_gmt":"2012-10-17T08:28:19","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=5911"},"modified":"2023-01-17T13:39:10","modified_gmt":"2023-01-17T12:39:10","slug":"2268-convegno-dal-titolo-i-disabili-e-il-loro-domani","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/2268-convegno-dal-titolo-i-disabili-e-il-loro-domani\/","title":{"rendered":"Convegno dal titolo \u201cI disabili e il loro domani\u201d"},"content":{"rendered":"<p><span style=\"font-size: 12px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\"><em>CASSANO ALLO IONIO(CS)<\/em> &#8211; <\/span>Sabato 20 ottobre 2012, alle ore 11.00, a Cassano allo\u2019Ionio (Cosenza), presso il teatro comunale,<\/p>\n<p>  <!--more-->  <\/p>\n<p>si terr\u00e0 un convegno dal titolo \u201cI disabili e il loro domani\u201d.&nbsp;<br style=\"margin: 0px; padding: 0px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\" \/>Parteciperanno all\u2019iniziativa, moderata dallo scrivente, Giovanni Papasso, sindaco di Cassano all\u2019Ionio; Antonio Carlomagno, sindaco di Cerchiara di Calabria; Massimiliano Barci, sindaco di Cervicati; Gianluca Gallo, consigliere regionale e Francesco Volpentesta, responsabile ente Project Life Calabria.<br style=\"margin: 0px; padding: 0px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\" \/>L\u2019incontro render\u00e0 conto di un apposito corso (I disabili e il loro domani) che permetter\u00e0 a nove disabili visivi e uditivi di ottenere la qualifica di \u201cAddetto ai Servizi Amministrativi\u201d.<br style=\"margin: 0px; padding: 0px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\" \/><span style=\"font-size: 12px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\">Durante i lavori gli allievi che hanno partecipato a detto corso riceveranno un attestato.<\/span><br style=\"margin: 0px; padding: 0px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\" \/><span style=\"font-size: 12px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\">Il convegno \u00e8 organizzato dall\u2019ente di formazione professionale Project Life Calabria con la collaborazione del comune di Cassano all\u2019Ionio.<\/span><\/p>\n<p><span style=\"font-size: 12px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\">&nbsp;<\/span><\/p>\n<p><span style=\"font-size: 12px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\">Strill.it<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CASSANO ALLO IONIO(CS) &#8211; Sabato 20 ottobre 2012, alle ore 11.00, a Cassano allo\u2019Ionio (Cosenza), presso il teatro comunale,<\/p>\n","protected":false},"author":22,"featured_media":5912,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,18,5],"tags":[],"class_list":["post-5911","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-dai-comuni","category-old"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/5911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=5911"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/5911\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/5912"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=5911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=5911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=5911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}