{"id":59113,"date":"2016-07-09T15:55:13","date_gmt":"2016-07-09T13:55:13","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/badante-uccisa-ad-acri-fermato-anziano\/"},"modified":"2023-01-17T12:08:44","modified_gmt":"2023-01-17T11:08:44","slug":"99556-badante-uccisa-ad-acri-fermato-anziano","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/99556-badante-uccisa-ad-acri-fermato-anziano\/","title":{"rendered":"Badante uccisa ad Acri, fermato anziano"},"content":{"rendered":"<p><strong>L\u2019uomo avrebbe tentato di violentare la donna per poi accoltellarla.<\/strong><!--more--><br \/>\n&nbsp;<br \/>\nACRI (CS) \u2013 \u00c8 stato fermato con l&#8217;accusa di omicidio <strong>Angelo Brogno<\/strong>, l&#8217;uomo di 78 anni, trovato, nella notte, nella propria abitazione, ad <strong>Acri<\/strong>, assieme al cadavere della sua badante, una donna bulgara di 58 anni, che lo assisteva, uccisa a colpi di coltello (<span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/1178\">leggi qui<\/a><\/span>). Il decreto di fermo \u00e8 stato emesso dal sostituto p<strong>rocuratore della Repubblica di Cosenza Donatella Donato<\/strong> che sta coordinando le indagini sull&#8217;omicidio.<br \/>\n&nbsp;<br \/>\nL&#8217;uomo attualmente si trova in ospedale ad Acri dove \u00e8 stato portato per medicare delle ferite da taglio. Sarebbe stato lo stesso presunto assassino a chiamare i carabinieri, nella notte, riferendo di un&#8217;aggressione nei suoi e confronti e nei confronti della donna da parte di un gruppo di sconosciuti. Alla base del delitto, secondo quanto \u00e8 stato possibile apprendere, ci sarebbe per\u00f2 la tentata violenza da parte dell&#8217;anziano alla quale la donna si \u00e8 opposta. Nel 2012 Brogno era stato denunciato per tentata violenza sessuale ai danni di un&#8217;altra donna, altra sua badante, di 40 anni.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019uomo avrebbe tentato di violentare la donna per poi accoltellarla.<\/p>\n","protected":false},"author":22,"featured_media":59114,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[571,28],"tags":[],"class_list":["post-59113","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/59113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=59113"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/59113\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/59114"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=59113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=59113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=59113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}