{"id":5925,"date":"2012-10-17T11:26:36","date_gmt":"2012-10-17T09:26:36","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=5925"},"modified":"2023-01-17T13:39:12","modified_gmt":"2023-01-17T12:39:12","slug":"2275-sequestrati-beni-per-un-valore-di-210mila-euro-a-boss-bruzzese","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/2275-sequestrati-beni-per-un-valore-di-210mila-euro-a-boss-bruzzese\/","title":{"rendered":"Sequestrati beni per un valore di 210mila euro a boss Bruzzese"},"content":{"rendered":"<p><span style=\"font-size: 12px; line-height: 18.649999618530273px; background-color: #ffffff;\"><em>COSENZA<\/em> &#8211; Beni per un valore di 210 mila euro sono stati sequestrati dalla squadra mobile di&nbsp;<\/span><span style=\"font-size: 12px; line-height: 18.649999618530273px; background-color: #ffffff;\">Cosenza<\/span><span style=\"font-size: 12px; line-height: 18.649999618530273px; background-color: #ffffff;\">&nbsp;a Franco Bruzzese, 45 anni, <\/span><\/p>\n<p>  <!--more-->  <\/p>\n<p><span style=\"font-size: 12px; line-height: 18.649999618530273px; background-color: #ffffff;\">detenuto per una condanna a 12 anni e 6 mesi di reclusione per tentato omicidio. Bruzzese, ritenuto il boss dell&#8217;omonima cosca, e&#8217; stato arrestato nell&#8217;agosto scorso. Il provvedimento di sequestro dei beni e&#8217; stato emesso dai giudici della sezione misure di sorveglianza del tribunale di&nbsp;<\/span><span style=\"font-size: 12px; line-height: 18.649999618530273px; background-color: #ffffff;\">Cosenza<\/span><span style=\"font-size: 12px; line-height: 18.649999618530273px; background-color: #ffffff;\">. I beni sono un immobile, due automobili ed una moto.(ANSA).<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Beni per un valore di 210 mila euro sono stati sequestrati dalla squadra mobile di&nbsp;Cosenza&nbsp;a Franco Bruzzese, 45 anni,<\/p>\n","protected":false},"author":22,"featured_media":5926,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42,5],"tags":[],"class_list":["post-5925","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza","category-old"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/5925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=5925"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/5925\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/5926"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=5925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=5925"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=5925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}