{"id":59325,"date":"2016-07-15T12:55:27","date_gmt":"2016-07-15T10:55:27","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/provincia-cosenza-consiglio-prende-atto-della-decadenza-mario-occhiuto\/"},"modified":"2023-01-17T12:09:09","modified_gmt":"2023-01-17T11:09:09","slug":"100143-provincia-cosenza-consiglio-prende-atto-della-decadenza-mario-occhiuto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/100143-provincia-cosenza-consiglio-prende-atto-della-decadenza-mario-occhiuto\/","title":{"rendered":"Provincia di Cosenza, Consiglio prende atto della decadenza di Mario Occhiuto"},"content":{"rendered":"<p><strong>Approvato anche l&#8217;avvio delle procedure per indire le elezioni del nuovo presidente\u00a0dell&#8217;Ente.<\/strong><\/p>\n<p>&nbsp;<br \/>\n<!--more--><\/p>\n<p>COSENZA &#8211; Si \u00e8 riunito il Consiglio provinciale di Cosenza convocato da<strong> Graziano Di Natale<\/strong>, consigliere anziano. Il Consiglio ha votato la presa d&#8217;atto dell&#8217;ordinanza di decadenza dei consiglieri <strong>Lino Di Nardo e Piero Lucisano<\/strong> e del presidente Mario Occhiuto. Inoltre, il Consiglio ha approvato l&#8217;avvio delle procedure per indire le elezioni del nuovo presidente della Provincia. &#8220;Vorrei far notare &#8211; ha precisato Di Natale a margine dell&#8217;assise &#8211; che il Consiglio si \u00e8 riunito senza il supporto dell&#8217;ufficio di segreteria, perch\u00e9 una burocrazia malata impedisce ai dipendenti di svolgere il proprio ruolo, e questo perch\u00e9 non si vuol prendere atto delle sentenze e delle ordinanze. Se Occhiuto \u00e8 convinto di aver ragione perch\u00e9 da marzo ad oggi non ha firmato alcun atto? Anzi lo sfido a firmarne almeno uno&#8221;. Entro fine mese il Consiglio deve approvare il bilancio, atto obbligatorio altrimenti decade l&#8217;organismo consiliare e i dipendenti non potranno essere pagati.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Approvato anche l&#8217;avvio delle procedure per indire le elezioni del nuovo presidente\u00a0dell&#8217;Ente. &nbsp;<\/p>\n","protected":false},"author":22,"featured_media":59326,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-59325","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/59325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=59325"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/59325\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/59326"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=59325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=59325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=59325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}