{"id":59405,"date":"2016-07-18T08:25:03","date_gmt":"2016-07-18T06:25:03","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/ndrangheta-tentati-omicidi-lamezia-terme-un-fermo\/"},"modified":"2023-01-17T12:09:18","modified_gmt":"2023-01-17T11:09:18","slug":"100375-ndrangheta-tentati-omicidi-lamezia-terme-un-fermo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/100375-ndrangheta-tentati-omicidi-lamezia-terme-un-fermo\/","title":{"rendered":"&#8216;Ndrangheta: due tentativi di omicidio a Lamezia Terme, un fermo"},"content":{"rendered":"<p><strong>I carabinieri hanno fatto luce sui tentativi di omicidio di Giuseppe Morello e Pasquale Saladino avvenuti, rispettivamente, nel novembre e dicembre del 2011 a Lamezia Terme.<\/strong><\/p>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>CATANZARO &#8211; Le indagini condotte in questi anni avrebbero permesso di individuare gli autori del gesto nonch\u00e9 di inquadrare il contesto in cui matur\u00f2. I carabinieri del nucleo investigativo del Comando provinciale di Catanzaro e della Compagnia di Lamezia Terme hanno notificato questa mattina, un fermo di indiziato di delitto emesso dalla Dda di Catanzaro per tentato omicidio premeditato in concorso aggravato dalle modalit\u00e0 mafiose. Il presunto reo avrebbe programmato, organizzato e direttamente compiuto le diverse azioni delittuose in cui tra l&#8217;altro, in una di esse, rimase ferito un bambino.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I carabinieri hanno fatto luce sui tentativi di omicidio di Giuseppe Morello e Pasquale Saladino avvenuti, rispettivamente, nel novembre e dicembre del 2011 a Lamezia Terme.<\/p>\n","protected":false},"author":22,"featured_media":59406,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-59405","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/59405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=59405"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/59405\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/59406"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=59405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=59405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=59405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}